{"id":7289,"date":"2018-07-02T14:57:41","date_gmt":"2018-07-02T14:57:41","guid":{"rendered":"https:\/\/emailchef.com\/?p=7289"},"modified":"2018-07-19T13:00:31","modified_gmt":"2018-07-19T13:00:31","slug":"pronti-partenza-via-ecco-il-blog-di-emailchef","status":"publish","type":"post","link":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/","title":{"rendered":"Pronti, partenza, via! Ecco il blog di Emailchef"},"content":{"rendered":"<h2>Il tuo nuovo punto di riferimento per l&#8217;email marketing<\/h2>\n<p>Vuoi catturare l\u2019attenzione dei tuoi clienti e instaurare un rapporto di fiducia con loro? Vuoi automatizzare le tue email, ma non sai come fare? Hai paura che il tuo <strong>email marketing<\/strong> non sia pi\u00f9 <strong>conforme alle nuove normative<\/strong>? Niente panico! \u00c8 nato <strong>il nuovo blog Emailchef<\/strong>!<\/p>\n<p>Su Emailchef Academy troverai tanti consigli utili che <strong>faciliteranno il lavoro di creazione e gestione delle tue newsletter<\/strong>!<\/p>\n<p>Se non l&#8217;hai ancora fatto, <strong><a class=\"fancybox-iframe\" href=\"https:\/\/app.emailchef.com\/signup\/form\/7o22666s726q5s6964223n2231353034227q\">iscriviti al nostro blog<\/a><\/strong> e scopri come utilizzare il tuo account Emailchef per sfruttare al meglio l&#8217;email marketing!<br \/>\nOgni mese riceverai idee per i tuoi template, consigli e aggiornamenti sfornati direttamente dai nostri esperti!<\/p>\n<p>Se dovessi avere qualche dubbio o domanda particolare sull&#8217;argomento dei post, <strong>scrivilo nei commenti<\/strong> cos\u00ec potremo <strong>darti l&#8217;approfondimento che cerchi<\/strong>!<\/p>\n<p>Buon Email Marketing!\u00a0 ???<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scopri come utilizzare al meglio il tuo account Emailchef e far fruttare il tuo email marketing! Sul blog Emailchef trovi idee per i tuoi template, consigli strategici e aggiornamenti sul mondo delle newsletter, sfornati direttamente dai nostri esperti.<\/p>\n","protected":false},"author":1,"featured_media":7375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[126],"tags":[],"class_list":["post-7289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-emailchef-academy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pronti, partenza, via! Ecco il blog di Emailchef - Emailchef<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emailchef\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/\"},\"author\":{\"name\":\"Emailchef\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/person\\\/3ee01193b4979523b9fbb53ecb80bb72\"},\"headline\":\"Pronti, partenza, via! Ecco il blog di Emailchef\",\"datePublished\":\"2018-07-02T14:57:41+00:00\",\"dateModified\":\"2018-07-19T13:00:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/\"},\"wordCount\":143,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/welcome-to-emailchef-email-marketing-blog-636x357.jpg\",\"articleSection\":[\"Emailchef Academy\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/\",\"name\":\"Pronti, partenza, via! Ecco il blog di Emailchef - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/welcome-to-emailchef-email-marketing-blog-636x357.jpg\",\"datePublished\":\"2018-07-02T14:57:41+00:00\",\"dateModified\":\"2018-07-19T13:00:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/welcome-to-emailchef-email-marketing-blog-636x357.jpg\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/welcome-to-emailchef-email-marketing-blog-636x357.jpg\",\"width\":636,\"height\":357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/pronti-partenza-via-ecco-il-blog-di-emailchef\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pronti, partenza, via! Ecco il blog di Emailchef\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/person\\\/3ee01193b4979523b9fbb53ecb80bb72\",\"name\":\"Emailchef\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fd1170c46b5af2a23c73c7dfa6a149de4ce1c9424a8b781423520eb8f0465a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fd1170c46b5af2a23c73c7dfa6a149de4ce1c9424a8b781423520eb8f0465a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fd1170c46b5af2a23c73c7dfa6a149de4ce1c9424a8b781423520eb8f0465a2?s=96&d=mm&r=g\",\"caption\":\"Emailchef\"},\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/author\\\/mailchef\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pronti, partenza, via! Ecco il blog di Emailchef - Emailchef","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/","twitter_misc":{"Scritto da":"Emailchef","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/#article","isPartOf":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/"},"author":{"name":"Emailchef","@id":"https:\/\/www.emailchef.com\/#\/schema\/person\/3ee01193b4979523b9fbb53ecb80bb72"},"headline":"Pronti, partenza, via! Ecco il blog di Emailchef","datePublished":"2018-07-02T14:57:41+00:00","dateModified":"2018-07-19T13:00:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/"},"wordCount":143,"commentCount":2,"publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/07\/welcome-to-emailchef-email-marketing-blog-636x357.jpg","articleSection":["Emailchef Academy"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/","url":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/","name":"Pronti, partenza, via! Ecco il blog di Emailchef - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/07\/welcome-to-emailchef-email-marketing-blog-636x357.jpg","datePublished":"2018-07-02T14:57:41+00:00","dateModified":"2018-07-19T13:00:31+00:00","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/#primaryimage","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/07\/welcome-to-emailchef-email-marketing-blog-636x357.jpg","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/07\/welcome-to-emailchef-email-marketing-blog-636x357.jpg","width":636,"height":357},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/pronti-partenza-via-ecco-il-blog-di-emailchef\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Pronti, partenza, via! Ecco il blog di Emailchef"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emailchef.com\/#\/schema\/person\/3ee01193b4979523b9fbb53ecb80bb72","name":"Emailchef","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fd1170c46b5af2a23c73c7dfa6a149de4ce1c9424a8b781423520eb8f0465a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fd1170c46b5af2a23c73c7dfa6a149de4ce1c9424a8b781423520eb8f0465a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fd1170c46b5af2a23c73c7dfa6a149de4ce1c9424a8b781423520eb8f0465a2?s=96&d=mm&r=g","caption":"Emailchef"},"url":"https:\/\/www.emailchef.com\/it\/author\/mailchef\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/7289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=7289"}],"version-history":[{"count":8,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/7289\/revisions"}],"predecessor-version":[{"id":7386,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/7289\/revisions\/7386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media\/7375"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=7289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/categories?post=7289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/tags?post=7289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}