{"id":58174,"date":"2023-01-08T13:38:47","date_gmt":"2023-01-08T13:38:47","guid":{"rendered":"https:\/\/emailchef.com\/?p=58174"},"modified":"2024-07-16T14:50:58","modified_gmt":"2024-07-16T14:50:58","slug":"come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list","status":"publish","type":"post","link":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/","title":{"rendered":"Come evitare che le tue newsletter finiscano in una black list"},"content":{"rendered":"<h2>Spam e black list sono l&#8217;incubo di chi si occupa di e-mail marketing (e non solo per il rischio di preparare contenuti che non legger\u00e0 nessuno).<\/h2>\n<p>Secondo gli esperti, <a href=\"https:\/\/securelist.com\/spam-report-2019\/96527\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">oltre la met\u00e0 delle e-mail inviate ogni giorno viene classificata come spam<\/a>. Senza contare che sono sempre di pi\u00f9 i domini che vengono inseriti nelle black list. <\/p>\n<p>Se ti occupi di e-mail marketing, probabilmente non ti sto dicendo nulla di nuovo. <\/p>\n<p>Ma il rischio non \u00e8 solo quello di scrivere contenuti che non legger\u00e0 nessuno (sprecando cos\u00ec tempo e fatica).<\/p>\n<p>Infatti, continuare a inviare newsletter che finiscono nello spam <strong>\u00e8 un modo semplice per distruggere la tua reputazione e perdere credibilit\u00e0<\/strong> alla velocit\u00e0 della luce.<\/p>\n<p>Ma esistono alcune strategie per evitare situazioni come questa. Qualche esempio? <\/p>\n<p>Inviare contenuti pertinenti e dare agli abbonati la possibilit\u00e0 di cancellarsi dalla mailing list.<\/p>\n<p>In questo articolo vedremo alcuni dei motivi pi\u00f9 comuni per cui le e-mail vengono spedite nello spam e ti dar\u00f2 qualche suggerimento per evitare di finire nelle black list dei client.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-58290\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter-junk.jpeg\" alt=\"Come evitare che la newsletter finisca nello spam.\" width=\"1200\" height=\"800\" \/><\/p>\n<h3 style=\"margin-top: 2em;\">Perch\u00e9 si finisce nelle black list (e quanto \u00e8 alto il rischio che le e-mail finiscano nello spam).<\/h3>\n<p>Le newsletter sono un ottimo strumento per raggiungere i tuoi obiettivi di marketing, a condizione che i contenuti che invii siano effettivamente recapitati ai tuoi contatti. Pu\u00f2 sembrare ovvio, eppure <a href=\"https:\/\/www.forbes.com\/sites\/daveywinder\/2020\/05\/03\/this-surprisingly-simple-email-trick-will-stop-spam-with-one-click\/?sh=3bd00de03791\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">secondo quanto condiviso da Forbes sono oltre 300 miliardi le e-mail che ogni giorno vengono classificate come spam<\/a>. <\/p>\n<p>Sar\u00e0 capitato anche a te di attendere un messaggio che per\u00f2 sembrava proprio non arrivare. <\/p>\n<p>E dove era finito? <\/p>\n<p>Magari proprio nella cartella della posta indesiderata.<\/p>\n<p><strong>Questo succede a causa dei filtri antispam<\/strong>. Purtroppo sono sempre di pi\u00f9 gli artefici di truffe via e-mail ed \u00e8 per questo motivo che le regole per non finire nelle black list dei provider sono sempre pi\u00f9 stringenti.<\/p>\n<p>Ma attenzione: se i contenuti che hai preparato vengono spediti nello spam, il rischio non \u00e8 solo che i tuoi abbonati non li leggeranno mai. Come se ci\u00f2 non fosse abbastanza, il tuo indirizzo e-mail verr\u00e0 compromesso e questo <strong>distrugger\u00e0 la tua reputazione<\/strong>.<\/p>\n<p>Non suona molto bene, vero?<\/p>\n<p>Ho per\u00f2 una buona notizia: \u00e8 possibile evitare di finire nello spam. Ma prima di spiegarti come (lo vedremo nel prossimo paragrafo) \u00e8 necessario fare 2 premesse.<\/p>\n<ol class=\"ol-list\" style=\"margin-bottom: 1em;\">\n<li style=\"margin-bottom: 1em;\">Lo scopo delle black list \u00e8 quello di <strong>proteggere gli utenti<\/strong> dal marketing aggressivo, monotematico e ad alta frequenza. Ne consegue che faresti meglio a evitare questo genere di comunicazione.<\/li>\n<li>Non sono solo i provider a poterti segnalare come spam: <strong>potrebbero farlo i tuoi stessi lettori<\/strong>. Ed ecco che ti sar\u00e0 impossibile raggiungere quelle caselle di posta anche in futuro. I motivi potrebbero essere diversi: magari il destinatario sta ricevendo contenuti che non ritiene pertinenti, le e-mail che gli invii sono troppe oppure potrebbe aver dimenticato di essersi iscritto alla newsletter.<\/li>\n<\/ol>\n<p>Ma esistono altri modi per finire nello spam. Magari i tuoi contenuti non sono classificabili come aggressivi e i tuoi contatti vorrebbero davvero leggere la tua newsletter, eppure i messaggi che spedisci potrebbero finire dritti tra quelli indesiderati. <\/p>\n<p>Perch\u00e9 succede?<\/p>\n<p>In casi come questo, \u00e8 possibile che tu stia spedendo <strong>newsletter con un alto tasso di bounce<\/strong>. E ti spiego subito cosa significa.<\/p>\n<p>Hai presente quando sbagli inserendo i dati di un indirizzo e-mail e ricevi un messaggio di posta che dice &#8220;Undelivered Mail Returned to Sender&#8221;? Per intenderci, \u00e8 quello che trovi qui sotto.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-58192 aligncenter\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter-Undelivered.jpeg\" alt=\"Undelivered Mail Returned to Sender: come evitare di far finire la newsletter nella black list\" width=\"879\" height=\"551\" \/><\/p>\n<p>Ecco, in casi come questo avrai avuto un bounce (che in inglese significa letteralmente &#8220;rimbalzo&#8221;). <\/p>\n<p>Se molti degli indirizzi inseriti nella tua mailing list sono errati o magari non esistono pi\u00f9, ecco che i sistemi di controllo della posta elettronica suoneranno e <strong>verrai etichettato come spammer<\/strong>. <\/p>\n<p>Fortunatamente c&#8217;\u00e8 un modo per sapere se la tua newsletter ha un elevato tasso di bounce. <\/p>\n<p>Emailchef ti permette infatti di tenere sotto controllo l&#8217;andamento della tua comunicazione via e-mail. Cos\u00ec, ti sar\u00e0 possibile conoscere anche la percentuale di rimbalzo dei contenuti che prepari.<\/p>\n<p>Trovi questi dati, divisi per campagna, facendo clic su &#8220;Statistiche&#8221;, nel men\u00f9 laterale a sinistra sulla piattaforma. In questo modo potrai verificare la percentuale di Bounce delle tue newsletter ed eventualmente effettuare una pulizia della tua mailing list.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-58206\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter-bounce-emailchef.jpeg\" alt=\"Conoscere il tasso di bounce per evitare che le newsletter finiscano nelle blck list\" width=\"1200\" height=\"419\" \/><\/p>\n<h3>Qualche consiglio utile per evitare le black list (e lo spam).<\/h3>\n<p>Per evitare di finire in una black list o di essere segnalati per spam, \u00e8 necessario garantire il rispetto di 3 misure:<\/p>\n<ol class=\"ol-list\" style=\"margin-bottom: 1em;\">\n<li style=\"margin-bottom: 1em;\">non inviare (MAI) e-mail se i tuoi contatti <strong>non ti hanno autorizzato in modo esplicito a farlo<\/strong>;<\/li>\n<li style=\"margin-bottom: 1em;\"><strong>non comprare mai liste<\/strong> di contatti da terzi;<\/li>\n<li>assicurati che ogni newsletter dia la <strong>possibilit\u00e0 agli iscritti di cancellarsi dalla mailing list<\/strong>.<\/li>\n<\/ol>\n<p>Dimenticare il rispetto di queste regole \u00e8 infatti il modo pi\u00f9 veloce per essere inseriti in una black list. <\/p>\n<p>Il motivo?<\/p>\n<p>Violando queste 3 indicazioni, starai infrangendo le <a href=\"https:\/\/gdpr-info.eu\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">indicazioni del GDPR<\/a> (e correrai parecchi problemi legali). Per saperne di pi\u00f9, ti consiglio la lettura dell&#8217;<a href=\"https:\/\/emailchef.com\/it\/blog-emailchef-academy\/con-emailchef-fare-newsletter-a-prova-di-gdpr-e-facile\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\" title=\"Come preparare newsletter che rispettino il regolamento GDPR\">articolo su come preparare newsletter che rispettino il regolamento<\/a>.<\/p>\n<p>Ma oltre a queste 3 indicazioni imprescindibili, esistono altri modi per evitare di finire tra la posta indesiderata.<\/p>\n<p>Uno \u00e8 quello di <strong>chiedere ai nuovi iscritti di inserire il tuo indirizzo nella lista dei contatti attendibili<\/strong>. Nel momento in cui qualcuno compila il form di iscrizione, avvisalo che ricever\u00e0 un&#8217;e-mail di verifica per confermare la registrazione. Nel caso in cui non dovesse riceverla, chiedigli di controllare nello spam e, se l&#8217;e-mail si trova qui, di contrassegnarla come &#8220;NON SPAM&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58226\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter-NONSPAM.jpeg\" alt=\"Segnala come NON SPAM per evitare di far finire la newsletter nello spam\" width=\"1195\" height=\"181\" \/><\/p>\n<p>Questo \u00e8 un ottimo modo per evitare di finire fin da subito tra la posta indesiderata.<\/p>\n<p>Esistono poi alcuni strumenti in grado di dirti se il tuo indirizzo e-mail \u00e8 finito in una black list. Infatti, se i client reputano pericoloso o inaffidabile il tuo dominio, ti sar\u00e0 impossibile raggiungere i tuoi contatti.\u00a0<\/p>\n<p>Per sapere se il tuo indirizzo \u00e8 stato registrato in una black list, ti consiglio di verificarlo tramite <a href=\"https:\/\/mxtoolbox.com\/SuperTool.aspx?action=blacklist%3agmail.com&amp;run=toolpage\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">MxToolbox<\/a>. Si tratta di uno strumento gratuito che ti consente di controllare se il tuo contatto \u00e8 stato inserito tra gli indirizzi potenzialmente pericolosi. <\/p>\n<p>Una volta aperto il sito, seleziona la voce &#8220;Black list&#8221; e inserisci il nome del tuo dominio. <strong>Il software ti dir\u00e0 se \u00e8 stato inserito o meno in una lista nera<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58240\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter-mxtooll.jpeg\" alt=\"usare mxtoolbox per vedere se la tua newsletter \u00e8 stata aggiunta a una black list\" width=\"1200\" height=\"639\" \/><\/p>\n<p>Se il programma rileva che l&#8217;indirizzo in questione \u00e8 stato inserito in una black list, ti permette di richiederne la rimozione facendo clic su &#8220;Click here for some suggestions&#8221;. In questo caso il servizio \u00e8 riservato agli abbonati premium.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58254\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter-blacklist-suggestion.jpeg\" alt=\"Consigli per rimuovere un indirizzo dalla black list\" width=\"1200\" height=\"641\" \/><\/p>\n<p>Un ultimo consiglio \u00e8 quello di <strong>prestare attenzione all&#8217;oggetto<\/strong>. Esistono infatti alcune indicazioni che dovresti sempre seguire per non finire nello spam. Qualche esempio?<\/p>\n<ul class=\"ul-list\" data-mark=\"-\" style=\"margin-bottom: 1em;\">\n<li>Non scrivere tutto l&#8217;oggetto in maiuscolo;<\/li>\n<li>Evita di inserire troppi elementi di punteggiatura o altri simboli;<\/li>\n<li>Non aggiungere troppi numeri;<\/li>\n<li>\n<p>Non inviare messaggi con oggetti ingannevoli o non pertinenti col contenuto dell&#8217;e-mail.<\/p>\n<\/li>\n<\/ul>\n<h3 style=\"margin-top: 2em;\">Spam e black list: i giusti strumenti per l&#8217;e-mail marketing possono aiutarti a tenere sotto controllo le tue campagne.<\/h3>\n<p>Molti dei contenuti che vengono inviati ogni giorno finiscono nello spam. Spedire troppe newsletter, scrivere dei messaggi ingannevoli o violare le regole del GDPR sono solo 3 tra i modi pi\u00f9 comuni per finire tra la posta indesiderata. Se poi il tuo indirizzo dovesse essere identificato come pericoloso, rischierebbe di essere inserito in una black list (e addio alla possibilit\u00e0 di raggiungere i tuoi contatti).<\/p>\n<p>Esistono per\u00f2 dei software in grado di dirti se il tuo dominio \u00e8 stato registrato in una lista nera, aiutandoti a rimuoverlo se classificato come pericoloso.<\/p>\n<p>Ricorda poi che<strong> i giusti strumenti per l&#8217;e-mail marketing ti permettono di preparare campagne che puoi tenere sempre sotto controllo<\/strong>, verificandone in ogni momento l&#8217;andamento e consentendoti di intervenire se necessario.<\/p>\n<p>Per questo<a href=\"https:\/\/app.emailchef.com\/apps\/demo\/quicksignup\" title=\"Prova gratis Emailchef\"> ti invito a fare subito una prova gratuita della nostra piattaforma<\/a>.<\/p>\n<p>Hai qualche dubbio? <a href=\"https:\/\/emailchef.com\/it\/contatti\/\" title=\"Contatta il team di Emailchef\">Contattaci<\/a>. Il team di Emailchef \u00e8 a tua disposizione!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spam e black list sono l\u2019incubo di chi si occupa di e-mail marketing (e non solo per il rischio di preparare contenuti che non legger\u00e0 nessuno).<\/p>\n","protected":false},"author":32,"featured_media":58176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[126],"tags":[],"class_list":["post-58174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-emailchef-academy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come evitare che le newsletter finiscano in una black list - Emailchef<\/title>\n<meta name=\"description\" content=\"Come Evitare che la Newsletter finisca in una Black List. Come Preparare un&#039;Email che Non Finisca nello Spam. Evita la Posta Indesiderata. &gt;&gt; Scopri come!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luca Marras\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/\"},\"author\":{\"name\":\"Luca Marras\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/person\\\/c3bfa1a7c9752c79c657d2fbb0559fd7\"},\"headline\":\"Come evitare che le tue newsletter finiscano in una black list\",\"datePublished\":\"2023-01-08T13:38:47+00:00\",\"dateModified\":\"2024-07-16T14:50:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/\"},\"wordCount\":1262,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/black-list-newsletter.jpeg\",\"articleSection\":[\"Emailchef Academy\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/\",\"name\":\"Come evitare che le newsletter finiscano in una black list - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/black-list-newsletter.jpeg\",\"datePublished\":\"2023-01-08T13:38:47+00:00\",\"dateModified\":\"2024-07-16T14:50:58+00:00\",\"description\":\"Come Evitare che la Newsletter finisca in una Black List. Come Preparare un'Email che Non Finisca nello Spam. Evita la Posta Indesiderata. >> Scopri come!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/black-list-newsletter.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/black-list-newsletter.jpeg\",\"width\":1200,\"height\":674,\"caption\":\"Evitare che la newsletter finisca nella black list\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come evitare che le tue newsletter finiscano in una black list\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/person\\\/c3bfa1a7c9752c79c657d2fbb0559fd7\",\"name\":\"Luca Marras\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g\",\"caption\":\"Luca Marras\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/lucamarras\\\/\"],\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/author\\\/luca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come evitare che le newsletter finiscano in una black list - Emailchef","description":"Come Evitare che la Newsletter finisca in una Black List. Come Preparare un'Email che Non Finisca nello Spam. Evita la Posta Indesiderata. >> Scopri come!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/","twitter_misc":{"Scritto da":"Luca Marras","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/#article","isPartOf":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/"},"author":{"name":"Luca Marras","@id":"https:\/\/www.emailchef.com\/#\/schema\/person\/c3bfa1a7c9752c79c657d2fbb0559fd7"},"headline":"Come evitare che le tue newsletter finiscano in una black list","datePublished":"2023-01-08T13:38:47+00:00","dateModified":"2024-07-16T14:50:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/"},"wordCount":1262,"commentCount":0,"publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter.jpeg","articleSection":["Emailchef Academy"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/","url":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/","name":"Come evitare che le newsletter finiscano in una black list - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter.jpeg","datePublished":"2023-01-08T13:38:47+00:00","dateModified":"2024-07-16T14:50:58+00:00","description":"Come Evitare che la Newsletter finisca in una Black List. Come Preparare un'Email che Non Finisca nello Spam. Evita la Posta Indesiderata. >> Scopri come!","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/#primaryimage","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter.jpeg","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/07\/black-list-newsletter.jpeg","width":1200,"height":674,"caption":"Evitare che la newsletter finisca nella black list"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/come-evitare-che-le-tue-newsletter-finiscano-in-una-black-list\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come evitare che le tue newsletter finiscano in una black list"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emailchef.com\/#\/schema\/person\/c3bfa1a7c9752c79c657d2fbb0559fd7","name":"Luca Marras","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g","caption":"Luca Marras"},"sameAs":["https:\/\/www.linkedin.com\/in\/lucamarras\/"],"url":"https:\/\/www.emailchef.com\/it\/author\/luca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/58174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=58174"}],"version-history":[{"count":13,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/58174\/revisions"}],"predecessor-version":[{"id":62204,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/58174\/revisions\/62204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media\/58176"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=58174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/categories?post=58174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/tags?post=58174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}