{"id":15740,"date":"2020-01-13T11:16:28","date_gmt":"2020-01-13T11:16:28","guid":{"rendered":"https:\/\/emailchef.com\/?p=15740"},"modified":"2020-01-24T11:00:07","modified_gmt":"2020-01-24T11:00:07","slug":"13-trend-per-la-tua-strategia-di-email-marketing-nel-2020","status":"publish","type":"post","link":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/","title":{"rendered":"13 trend per la tua strategia di email marketing nel 2020"},"content":{"rendered":"<p>I mercati hanno parlato: con l\u2019inizio del nuovo anno si moltiplicano i segni che indicano nella strategia nei confronti dell&#8217;<strong>email marketing<\/strong> per il 2020 una componente importante per la vita delle aziende, in particolare quando si tratta di <strong>promozione del brand<\/strong> e di<strong> coinvolgimento di clienti<\/strong>, sia consolidati che potenziali.<\/p>\n<p>Nel suo ultimo <strong>report sullo stato dell\u2019email marketing<\/strong>, <a href=\"https:\/\/www.validity.com\/resources\/products\/REPORT-ReturnPath-The-State-of-Email-Marketing-2019.pdf\" target=\"_blank\" rel=\"noopener\">Demand Metrics<\/a> snocciola le opinioni delle imprese che usano stabilmente questo strumento nel lavoro di tutti i giorni.<\/p>\n<p>Abbiamo selezionato per te alcuni <strong>trend<\/strong> che secondo noi sono i <strong>pi\u00f9 interessanti<\/strong>.<\/p>\n<h3>Obiettivo &#8211; promuovere la crescita del brand<\/h3>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1.png\" rel=\"lightbox\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-15772 size-large\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1-1024x852.png\" alt=\"statistiche email marketing\" width=\"686\" height=\"571\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1-1024x852.png 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1-300x250.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1-768x639.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1-968x806.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1-636x529.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1-320x266.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1-239x199.png 239w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-1.png 1068w\" sizes=\"(max-width: 686px) 100vw, 686px\" \/><\/a><\/p>\n<p>1 &#8211; Investire tempo e risorse nell&#8217;email marketing si dimostra essere un valore aggiunto. Le aziende che fanno campagne in modo professionale vedono i <strong>risultati<\/strong> e un <strong>ritorno in termini di maggiore conoscenza del brand e interesse verso l&#8217;azienda<\/strong>.<\/p>\n<p>2- I dati raccolti tra le aziende dimostrano che l\u2019uso ragionato di una piattaforma di email marketing \u00e8 tra le componenti che <strong>favorisce la crescita<\/strong>, pur non potendo costituire l\u2019unico rimedio di fronte a uno stato di crisi.<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2.png\" rel=\"lightbox\"><img decoding=\"async\" class=\"aligncenter wp-image-15786 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2.png\" alt=\"statistiche email marketing\" width=\"1068\" height=\"775\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2.png 1068w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2-300x218.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2-768x557.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2-1024x743.png 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2-968x702.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2-636x462.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2-320x232.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-2-239x173.png 239w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><\/a><\/p>\n<h3>Sfida &#8211; ottenere l&#8217;attenzione degli utenti<\/h3>\n<p>3 &#8211; La \u201cgara\u201d per <strong>conquistare l\u2019attenzione dell\u2019utente all\u2019interno della sua casella di posta<\/strong> rimane la principale sfida dell\u2019email marketing nel 2020. Per questo, <strong>investire per aumentare l&#8217;efficacia<\/strong> delle campagne di email marketing (attraverso l&#8217;uso di piattaforme professionali) pagher\u00e0 in termini di tassi di apertura delle email pi\u00f9 elevati.<\/p>\n<p>4 &#8211; Se <strong>l&#8217;obiettivo \u00e8 aumentare ricavi e fatturato<\/strong>, l&#8217;email marketing si dimostra uno strumento ottimale e i tassi di apertura delle campagne sono migliori rispetto a chi invia le email solo a scopo informativo e magari in modo saltuario.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3.png\" rel=\"lightbox\"><img decoding=\"async\" class=\"alignnone wp-image-15800 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3.png\" alt=\"statistiche email marketing\" width=\"1068\" height=\"775\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3.png 1068w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3-300x218.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3-768x557.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3-1024x743.png 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3-968x702.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3-636x462.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3-320x232.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-3-239x173.png 239w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><\/a><\/p>\n<p>5 &#8211; Le imprese si organizzano aumentando l&#8217;uso di risorse e competenze affidate a terzi, sia attraverso l&#8217;<strong>outsourcing<\/strong> oppure la collaborazione tra risorse in house ed altre esterne. <strong>Le aziende B2C sono pi\u00f9 disposte a investire in risorse esterne<\/strong> per supportare le attivit\u00e0 di email marketing.<\/p>\n<h3>Strategia &#8211; usare servizi professionali<\/h3>\n<p>6 &#8211; Quali sono le <strong>tattiche in uso da parte delle aziende che godono di tassi di apertura delle email medio-alti<\/strong> (dal 16% in su)? Ai primi posti troviamo la personalizzazione delle email e dell\u2019oggetto, il lavoro per migliorare la deliverability e la manutenzione delle liste di contatti. Sono aspetti per cui <strong>\u00e8 necessario servirsi di piattaforme professionali dotate di funzionalit\u00e0 pi\u00f9 performanti<\/strong>, proprio come <strong>Emailchef<\/strong>.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4.png\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15814 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4.png\" alt=\"statistiche email marketing\" width=\"1068\" height=\"753\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4.png 1068w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4-300x212.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4-768x541.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4-1024x722.png 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4-968x682.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4-636x448.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4-320x226.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-4-239x169.png 239w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><\/a><\/p>\n<p>7 &#8211; La sola area in cui nel tempo si \u00e8 manifestata una variazione notevole, decisamente salutare per il settore, \u00e8 la <strong>riduzione dell&#8217;uso di liste di indirizzi email acquistate<\/strong>. Gli esperti di email marketing concordano sul fatto che i rischi derivanti da queste operazioni superano di gran lunga i vantaggi.<\/p>\n<p>8 &#8211; Per un\u2019azienda, lavorare con un processo consolidato di ottimizzazione delle email, per esempio <strong>prendere costantemente spunto dai rendimenti delle campagne passate<\/strong>, aiuta ad aumentare i tassi medi di apertura delle email.<\/p>\n<h3>Contatti &#8211; usare le informazioni<\/h3>\n<p>9 &#8211; <strong>Molte aziende<\/strong> che fanno email marketing<strong> non sfruttano <\/strong>affatto <strong>le informazioni di cui gi\u00e0 potrebbero disporre<\/strong> riguardo ai loro abbonati. Secondo Demand Metrics, le imprese affermano di conoscere importanti preferenze degli utenti, tra cui tipo di dispositivo usato per leggere le email, l\u2019orario di apertura dei messaggi e browser e client di posta utilizzati.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5.png\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15828 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5.png\" alt=\"statistiche email marketing\" width=\"1068\" height=\"856\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5.png 1068w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5-300x240.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5-768x616.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5-1024x821.png 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5-968x776.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5-636x510.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5-320x256.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-5-239x192.png 239w\" sizes=\"(max-width: 1068px) 100vw, 1068px\" \/><\/a><\/p>\n<p>10 &#8211; Oltre il 70% delle aziende sfrutta le <strong>tecnologie<\/strong> a disposizione <strong>per visualizzare l&#8217;anteprima delle email<\/strong> su vari dispositivi e client di posta. La generazione di preview \u00e8 un solo un esempio di come la tecnologia sia a disposizione per aiutare chi fa email marketing a migliorare le azioni promozionali.<\/p>\n<h3>Performance &#8211; generare conversioni<\/h3>\n<p>11- La <strong>relazione tra i tassi di apertura e di clic<\/strong> non \u00e8 cos\u00ec intuitiva come alcuni potrebbero pensare. In linea generale, pi\u00f9 aperture causano un maggior numero di clic sulle call to action. Ma un messaggio con un oggetto convincente, inviato da una societ\u00e0 che fa parte di una <a href=\"https:\/\/emailchef.com\/it\/documentazione\/configurare-white-label-mode\/\"><strong>whitelist certificata<\/strong><\/a>, potrebbe non generare clic a causa di un testo scritto male nel corpo dell&#8217;email.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1.png\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16490 size-large\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1-1024x527.png\" alt=\"\" width=\"686\" height=\"353\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1-1024x527.png 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1-300x154.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1-768x396.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1-968x499.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1-636x328.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1-320x165.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1-239x123.png 239w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/grafico-6-1.png 1068w\" sizes=\"(max-width: 686px) 100vw, 686px\" \/><\/a><\/p>\n<p>12 &#8211; Ovviamente, il rendimento di un messaggio di posta elettronica ben confezionato soffrir\u00e0 a causa di una riga dell&#8217;oggetto scritta senza cura o da un mancato testing per verificare la visualizzazione su client e device vari..<\/p>\n<p>13 &#8211; La relazione open e click rate suggerisce, pi\u00f9 di qualsiasi altra cosa, che i professionisti che seguono le buone pratiche per <strong>massimizzare l\u2019apertura delle email<\/strong> si impegnano allo stesso modo nella <strong>creazione di messaggi che generano conversioni<\/strong>.<\/p>\n<h3>Conclusioni<\/h3>\n<p><strong>Il costo delle piattaforme di email marketing nel 2020 \u00e8 ancora basso<\/strong> rispetto ad altri canali (es. social network e Google Ads), soprattutto di fronte al <strong>ritorno di investimento<\/strong> che \u00e8 reso possibile da un\u2019attivit\u00e0 costante e pianificata. La strategia principale consiste in:<strong><br \/>\n<\/strong><\/p>\n<ol>\n<li><strong>Inviare le email col <a href=\"https:\/\/emailchef.com\/it\/blog-emailchef-academy\/qual-e-la-frequenza-migliore-di-invio-delle-newsletter\/\">tempismo corretto<\/a><\/strong>, in modo che arrivino a destinazione nella casella di posta degli utenti nel momento in cui \u00e8 pi\u00f9 probabile che la vedano;<\/li>\n<li><strong>Creare <a href=\"https:\/\/emailchef.com\/it\/blog-emailchef-academy\/come-scrivere-un-oggetto-che-funziona-nel-email-marketing\/\">oggetti email<\/a> e contenuti editoriali<\/strong> che generino il massimo tasso di apertura, anche nell\u2019ottica di abituare gli utenti alla qualit\u00e0 dei tuoi messaggi;<\/li>\n<li>Strutturare i messaggi in base a <strong>strategie che generano altrettanti clic<\/strong> (conversioni).<\/li>\n<\/ol>\n<p>Volendo fare un elenco delle <strong>virt\u00f9 del professionista dell\u2019email marketing<\/strong>, potremmo riassumere che:<\/p>\n<ul>\n<li><strong>Si mette alla prova con obiettivi ambiziosi<\/strong>, perch\u00e9 questo \u00e8 di stimolo quando si tratta di realizzare una buona campagna di email marketing;<\/li>\n<li>Usa strategie che vanno dal <strong>coltivare la deliverability<\/strong> al <strong>lancio di<\/strong> <strong>campagne di riattivazione<\/strong> per gli utenti che hanno smesso di interagire con l\u2019azienda;<\/li>\n<li>Tiene le<strong> liste dei contatti pulite<\/strong> da indirizzi email che hanno fatto bounce o si sono disiscritti;<\/li>\n<li>Si ispira alle campagne email passate per <strong>ottimizzare<\/strong> sempre pi\u00f9<strong> la riga dell\u2019oggetto<\/strong>;<\/li>\n<li>Non teme di <strong>sperimentare le tecnologie<\/strong> come anteprime di invio, blacklist e whitelist per inseguire tassi di apertura pi\u00f9 alti;<\/li>\n<li><strong>\u00c8 iscritto alle mailing list dei concorrenti<\/strong>, come ulteriore mezzo per essere il pi\u00f9 possibile aggiornato.<\/li>\n<\/ul>\n<p><strong>E tu a che punto sei sulla strada per fare un ottimo email marketing?<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inviare email fa aumentare il fatturato delle imprese? Il tasso di clic cresce insieme al tasso di apertura? Ecco cosa dicono le aziende.<\/p>\n","protected":false},"author":11,"featured_media":15900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[126],"tags":[],"class_list":["post-15740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-emailchef-academy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13 trend per la tua strategia di email marketing nel 2020 - Emailchef<\/title>\n<meta name=\"description\" content=\"L\u2019email marketing nel 2020 \u00e8 una disciplina in piena fioritura. Ecco cosa dicono le aziende che usano l\u2019email marketing nel lavoro di tutti i giorni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/\"},\"author\":{\"name\":\"Michele\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/person\\\/f83eaaa673d777a37f58077c6d05d383\"},\"headline\":\"13 trend per la tua strategia di email marketing nel 2020\",\"datePublished\":\"2020-01-13T11:16:28+00:00\",\"dateModified\":\"2020-01-24T11:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/\"},\"wordCount\":974,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/em-trends-1.png\",\"articleSection\":[\"Emailchef Academy\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/\",\"name\":\"13 trend per la tua strategia di email marketing nel 2020 - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/em-trends-1.png\",\"datePublished\":\"2020-01-13T11:16:28+00:00\",\"dateModified\":\"2020-01-24T11:00:07+00:00\",\"description\":\"L\u2019email marketing nel 2020 \u00e8 una disciplina in piena fioritura. Ecco cosa dicono le aziende che usano l\u2019email marketing nel lavoro di tutti i giorni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/em-trends-1.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/em-trends-1.png\",\"width\":960,\"height\":540,\"caption\":\"email marketing 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"13 trend per la tua strategia di email marketing nel 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/person\\\/f83eaaa673d777a37f58077c6d05d383\",\"name\":\"Michele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/31319012b9c113b20ace66bfc87241b624c988b2c676ce8700dab03d449b63dd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/31319012b9c113b20ace66bfc87241b624c988b2c676ce8700dab03d449b63dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/31319012b9c113b20ace66bfc87241b624c988b2c676ce8700dab03d449b63dd?s=96&d=mm&r=g\",\"caption\":\"Michele\"},\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/author\\\/michele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13 trend per la tua strategia di email marketing nel 2020 - Emailchef","description":"L\u2019email marketing nel 2020 \u00e8 una disciplina in piena fioritura. Ecco cosa dicono le aziende che usano l\u2019email marketing nel lavoro di tutti i giorni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/","twitter_misc":{"Scritto da":"Michele","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/#article","isPartOf":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/"},"author":{"name":"Michele","@id":"https:\/\/www.emailchef.com\/#\/schema\/person\/f83eaaa673d777a37f58077c6d05d383"},"headline":"13 trend per la tua strategia di email marketing nel 2020","datePublished":"2020-01-13T11:16:28+00:00","dateModified":"2020-01-24T11:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/"},"wordCount":974,"commentCount":0,"publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/em-trends-1.png","articleSection":["Emailchef Academy"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/","url":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/","name":"13 trend per la tua strategia di email marketing nel 2020 - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/em-trends-1.png","datePublished":"2020-01-13T11:16:28+00:00","dateModified":"2020-01-24T11:00:07+00:00","description":"L\u2019email marketing nel 2020 \u00e8 una disciplina in piena fioritura. Ecco cosa dicono le aziende che usano l\u2019email marketing nel lavoro di tutti i giorni.","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/#primaryimage","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/em-trends-1.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/01\/em-trends-1.png","width":960,"height":540,"caption":"email marketing 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/13-trend-per-la-tua-strategia-di-email-marketing-nel-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"13 trend per la tua strategia di email marketing nel 2020"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emailchef.com\/#\/schema\/person\/f83eaaa673d777a37f58077c6d05d383","name":"Michele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/31319012b9c113b20ace66bfc87241b624c988b2c676ce8700dab03d449b63dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/31319012b9c113b20ace66bfc87241b624c988b2c676ce8700dab03d449b63dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/31319012b9c113b20ace66bfc87241b624c988b2c676ce8700dab03d449b63dd?s=96&d=mm&r=g","caption":"Michele"},"url":"https:\/\/www.emailchef.com\/it\/author\/michele\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/15740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=15740"}],"version-history":[{"count":16,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/15740\/revisions"}],"predecessor-version":[{"id":16504,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/15740\/revisions\/16504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media\/15900"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=15740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/categories?post=15740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/tags?post=15740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}