{"id":13156,"date":"2019-10-04T13:09:51","date_gmt":"2019-10-04T13:09:51","guid":{"rendered":"https:\/\/emailchef.com\/?p=13156"},"modified":"2024-07-16T14:37:51","modified_gmt":"2024-07-16T14:37:51","slug":"guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi","status":"publish","type":"post","link":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/","title":{"rendered":"Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi"},"content":{"rendered":"<p><strong>GDPR, CAN-spam <\/strong>e <strong>CSA<\/strong>: \u00e8 possibile che tu abbia incontrato una o pi\u00f9 di queste sigle durante il tuo lavoro. Si tratta in tutti casi di <strong>regolamenti che riguardano<\/strong> l\u2019ottenimento e l\u2019uso dei dati personali da parte di <strong>chi fa email marketing<\/strong>.<\/p>\n<p>Vediamo in dettaglio in cosa consiste ogni sigla e <strong>in che circostanze sei tenuto ad aderire all\u2019uno o all\u2019altro<\/strong>.<\/p>\n<h3>GDPR<\/h3>\n<p>Questo regolamento vale per <strong>tutte le email dirette verso i Paesi che fanno parte dell\u2019Unione Europea<\/strong> o inviate da uno di essi.<\/p>\n<p>In estrema sintesi, <strong>\u00e8 necessario che tu ottenga il consenso informato dell\u2019utente<\/strong> prima di iniziare a inviargli email. Egli inoltre deve essere messo nella condizione di poter revocare questo consenso con facilit\u00e0.<\/p>\n<p><a href=\"https:\/\/emailchef.com\/it\/blog-emailchef-academy\/email-marketing-e-gdpr-amici-o-nemici\/\">Abbiamo scritto un post<\/a> per spiegare bene l\u2019<strong>opportunit\u00e0 che il GDPR rappresenta<\/strong> per la tua attivit\u00e0 commerciale.<\/p>\n<p>Gli<strong> strumenti dell\u2019email marketing per implementare il GDPR nella tua strategia<\/strong> sono il modulo di opt-in per le registrazioni e l\u2019inserimento del link di disiscrizione in newsletter.<\/p>\n<p><a href=\"https:\/\/emailchef.com\/it\/blog-emailchef-academy\/con-emailchef-fare-newsletter-a-prova-di-gdpr-e-facile\/\"><strong>Scopri come \u00e8 facile organizzare questi elementi con Emailchef.<\/strong><\/a><\/p>\n<h3>CAN-spam<\/h3>\n<p>Questo regolamento \u00e8 il pi\u00f9 vecchio dei tre e riguarda tutte le email commerciali dirette verso utenti negli <strong>Stati Uniti<\/strong>.<\/p>\n<p>Puoi considerarlo una versione leggermente pi\u00f9 \u201csoft\u201d del GDPR, perch\u00e9<strong> non \u00e8 previsto l\u2019obbligo di ottenere il consenso esplicito dell\u2019utente per inviargli email<\/strong>. Questo si ottiene, per esempio, inserendo il box relativo gi\u00e0 selezionato nel modulo di registrazione.<\/p>\n<p>Infatti, il CAN-spam \u00e8 una legge che mette l\u2019accento sull\u2019opt-out piuttosto che sull\u2019opt-in. <strong>L\u2019utente deve poter opporsi all\u2019invio di ulteriori messaggi<\/strong> e questa scelta deve essere facilmente accessibile, e cio\u00e8 tramite un link di disiscrizione all\u2019interno delle email.<\/p>\n<p>Potresti trovare interessante sapere che anche il <strong>Canada<\/strong> ha il proprio regolamento in materia, la cui sigla \u00e8 <a href=\"https:\/\/www.osler.com\/en\/resources\/in-focus\/casl-compliance-more-than-spam-understanding-canada-s-anti-spam-law\" target=\"_blank\" rel=\"noopener\">CASL<\/a>.<\/p>\n<h3>CSA<\/h3>\n<p>Anche se questa sigla non \u00e8 il nome di un regolamento &#8211; sta infatti per <a href=\"https:\/\/certified-senders.org\/about-csa\/\" target=\"_blank\" rel=\"noopener\">Certified Senders Alliance<\/a> &#8211; l\u2019effetto pratico \u00e8 analogo. Le indicazioni che contiene non sono obbligatorie, ma rappresentano uno standard positivo a cui \u00e8 conveniente adeguarsi. La peculiarit\u00e0 \u00e8 che <strong>si applica esclusivamente al mercato tedesco<\/strong>.<\/p>\n<p>Entrando in dettaglio, <strong>le email commerciali<\/strong> dirette agli utenti in Germania <strong>devono contenere<\/strong> queste informazioni:<\/p>\n<ul>\n<li>Tutte ci\u00f2 che \u00e8 richiesto dal CAN-spam e dal GDPR, e cio\u00e8 nome dell\u2019azienda, indirizzo, codice postale, citt\u00e0 e nazione, link di disiscrizione;<\/li>\n<li>Nome e cognome del rappresentante legale dell\u2019azienda;<\/li>\n<li>Un numero di telefono (perfettamente funzionante) per contattarti;<\/li>\n<li>Un indirizzo email valido, che pu\u00f2 anche essere quello che da cui viene inviato il messaggio;<\/li>\n<li>Il link del sito internet aziendale;<\/li>\n<li>La partita IVA o il numero di registrazione.<\/li>\n<\/ul>\n<h3>Emailchef ti toglie ogni dubbio<\/h3>\n<p>Quando crei una newsletter <strong>con l\u2019editor di Emailchef<\/strong>, inserire le informazioni richieste per tutelare i dati personali ai sensi delle leggi <strong>\u00e8 un gioco da ragazzi<\/strong>.<\/p>\n<p><strong>Ecco come fare<\/strong>. Nel men\u00f9 a tendina dei blocchi<strong> seleziona \u201cPi\u00e8 di pagina\u201d<\/strong>. Se scegli di cliccare e trascinare nell\u2019area di lavoro l\u2019oggetto col nome \u201cCSA\u201d (marchiato con i colori della Germania) disporrai di un <strong>blocco precompilato con tutte le informazioni richieste<\/strong> da questo standard.<\/p>\n<p><strong>I blocchi con il nome \u201cCAN-spam act\u201d<\/strong>, disponibili in italiano, inglese, francese e spagnolo, contengono invece le <strong>informazioni richieste sia dal CAN-spam che dal GDPR<\/strong>.<\/p>\n<p><strong>Quali che siano i tuoi destinatari, hai solo due opzioni<\/strong>: mercato tedesco o resto del mondo. All\u2019interno dei blocchi, <strong>le voci che vedi tra parentesi quadra non sono da sostituire manualmente<\/strong>. Questa operazione sar\u00e0 effettuata in automatico da parte di Emailchef, che inserir\u00e0 le informazioni associate all\u2019indirizzo email verificato con il quale stai inviando. <strong>\u00c8 davvero semplice<\/strong>.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks.png\" rel=\"lightbox\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-12892 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks.png\" alt=\"gdpr can-spam blocks\" width=\"1438\" height=\"949\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks.png 1438w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks-300x198.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks-768x507.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks-1024x676.png 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks-968x639.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks-636x420.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks-320x211.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/09\/editor-compliance-blocks-239x158.png 239w\" sizes=\"(max-width: 1438px) 100vw, 1438px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GDPR, CAN-spam e CSA sono tutte regolamentazioni per l\u2019ottenimento e l\u2019uso dei dati personali da parte di chi fa email marketing. Vediamo in che circostanze sei tenuto ad aderire all\u2019uno o all\u2019altro.<\/p>\n","protected":false},"author":32,"featured_media":13164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[126],"tags":[],"class_list":["post-13156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-emailchef-academy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi - Emailchef<\/title>\n<meta name=\"description\" content=\"GDPR, CAN-spam e CSA regolano l\u2019ottenimento e l\u2019uso dei dati personali da parte di chi fa email marketing. Impara a conoscerli.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luca Marras\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/\"},\"author\":{\"name\":\"Luca Marras\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/person\\\/c3bfa1a7c9752c79c657d2fbb0559fd7\"},\"headline\":\"Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi\",\"datePublished\":\"2019-10-04T13:09:51+00:00\",\"dateModified\":\"2024-07-16T14:37:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/\"},\"wordCount\":601,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/gdpr-can-spam-cover.png\",\"articleSection\":[\"Emailchef Academy\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/\",\"name\":\"Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/gdpr-can-spam-cover.png\",\"datePublished\":\"2019-10-04T13:09:51+00:00\",\"dateModified\":\"2024-07-16T14:37:51+00:00\",\"description\":\"GDPR, CAN-spam e CSA regolano l\u2019ottenimento e l\u2019uso dei dati personali da parte di chi fa email marketing. Impara a conoscerli.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/gdpr-can-spam-cover.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/gdpr-can-spam-cover.png\",\"width\":968,\"height\":544,\"caption\":\"guida gdpr can-spam cosa sono\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/blog-emailchef-academy\\\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/person\\\/c3bfa1a7c9752c79c657d2fbb0559fd7\",\"name\":\"Luca Marras\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g\",\"caption\":\"Luca Marras\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/lucamarras\\\/\"],\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/author\\\/luca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi - Emailchef","description":"GDPR, CAN-spam e CSA regolano l\u2019ottenimento e l\u2019uso dei dati personali da parte di chi fa email marketing. Impara a conoscerli.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/","twitter_misc":{"Scritto da":"Luca Marras","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/#article","isPartOf":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/"},"author":{"name":"Luca Marras","@id":"https:\/\/www.emailchef.com\/#\/schema\/person\/c3bfa1a7c9752c79c657d2fbb0559fd7"},"headline":"Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi","datePublished":"2019-10-04T13:09:51+00:00","dateModified":"2024-07-16T14:37:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/"},"wordCount":601,"commentCount":0,"publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/10\/gdpr-can-spam-cover.png","articleSection":["Emailchef Academy"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/","url":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/","name":"Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/10\/gdpr-can-spam-cover.png","datePublished":"2019-10-04T13:09:51+00:00","dateModified":"2024-07-16T14:37:51+00:00","description":"GDPR, CAN-spam e CSA regolano l\u2019ottenimento e l\u2019uso dei dati personali da parte di chi fa email marketing. Impara a conoscerli.","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/#primaryimage","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/10\/gdpr-can-spam-cover.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2019\/10\/gdpr-can-spam-cover.png","width":968,"height":544,"caption":"guida gdpr can-spam cosa sono"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/blog-emailchef-academy\/guida-gdpr-can-spam-e-csa-cosa-sono-e-in-cosa-sono-diversi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Guida a GDPR, CAN-spam e CSA: cosa sono e in cosa sono diversi"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.emailchef.com\/#\/schema\/person\/c3bfa1a7c9752c79c657d2fbb0559fd7","name":"Luca Marras","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a03f60654d1d7987234aeb6dbc073a8dfb24d4f5b1a0c31be87611c227889fbf?s=96&d=mm&r=g","caption":"Luca Marras"},"sameAs":["https:\/\/www.linkedin.com\/in\/lucamarras\/"],"url":"https:\/\/www.emailchef.com\/it\/author\/luca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/13156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=13156"}],"version-history":[{"count":4,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/13156\/revisions"}],"predecessor-version":[{"id":13182,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/posts\/13156\/revisions\/13182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media\/13164"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=13156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/categories?post=13156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/tags?post=13156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}