{"id":85747,"date":"2025-09-01T09:48:14","date_gmt":"2025-09-01T09:48:14","guid":{"rendered":"https:\/\/emailchef.com\/?page_id=85747"},"modified":"2025-09-11T08:35:38","modified_gmt":"2025-09-11T08:35:38","slug":"punto-di-entrata-anniversario-del-contatto","status":"publish","type":"page","link":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/","title":{"rendered":"Punto di entrata: anniversario del contatto"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"85747\" class=\"elementor elementor-85747\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-822343a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"822343a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee1b24a\" data-id=\"ee1b24a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc9b6b2 elementor-widget elementor-widget-text-editor\" data-id=\"fc9b6b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il punto di entrata <em>Anniversario del contatto<\/em> si attiva in corrispondenza di una data specifica associata al contatto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0212ea2 elementor-widget elementor-widget-image\" data-id=\"0212ea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"355\" height=\"683\" src=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto.jpg\" class=\"attachment-large size-large wp-image-85749\" alt=\"Emailchef Flow: anniversario del contatto\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto.jpg 355w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-156x300.jpg 156w\" sizes=\"(max-width: 355px) 100vw, 355px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-912f24d elementor-widget elementor-widget-text-editor\" data-id=\"912f24d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questa data pu&ograve; essere, ad esempio:<\/p>\n<ul>\n<li style=\"margin-bottom: 10px;\">la <strong>data di iscrizione<\/strong> alla tua lista;<\/li>\n<li style=\"margin-bottom: 10px;\">un <strong>campo personalizzato di tipo data<\/strong>, come la data di nascita, una scadenza o un anniversario particolare.<\/li>\n<\/ul>\n<p>Puoi scegliere di avviare il flusso esattamente il giorno dell&rsquo;anniversario, oppure un certo numero di giorni prima o dopo.<\/p>\n<p>&Egrave; l&rsquo;ideale per inviare comunicazioni ricorrenti, promemoria o auguri personalizzati, cos&igrave; da far sentire il contatto seguito e valorizzato nel momento giusto.<\/p>\n<p>Un esempio pratico: puoi configurare un&rsquo;email di auguri che parte il giorno del compleanno del contatto, oppure un promemoria per rinnovare un abbonamento una settimana prima della data di scadenza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-629ff86 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"629ff86\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db2f72f\" data-id=\"db2f72f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1418895 elementor-widget elementor-widget-heading\" data-id=\"1418895\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Come configurare il trigger \u201cAnniversario del contatto\u201d.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bca480e elementor-widget elementor-widget-image\" data-id=\"bca480e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Emailchef flow: anniversario contatto\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6ODU3NTgsInVybCI6Imh0dHBzOlwvXC93d3cuZW1haWxjaGVmLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNVwvMDlcL2VtYWlsY2hlZi1mbG93LXB1bnRvLWluZ3Jlc3NvLWFubml2ZXJzYXJpby1jb250YXR0by0xLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-1.jpg\" class=\"attachment-large size-large wp-image-85758\" alt=\"Emailchef flow: anniversario contatto\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-1.jpg 1000w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-1-300x199.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-1-768x508.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13fc7d7 elementor-widget elementor-widget-heading\" data-id=\"13fc7d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Seleziona la lista di riferimento.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-759b97b elementor-widget elementor-widget-image\" data-id=\"759b97b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"495\" height=\"702\" src=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-2.jpg\" class=\"attachment-large size-large wp-image-85767\" alt=\"Emailchef flow: anniversario contatto\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-2.jpg 495w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-2-212x300.jpg 212w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c10d4 elementor-widget elementor-widget-text-editor\" data-id=\"c1c10d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per iniziare, scegli la lista che contiene i contatti da monitorare.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f1a719 elementor-widget elementor-widget-heading\" data-id=\"7f1a719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Scegli il campo data di riferimento.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8c322a elementor-widget elementor-widget-image\" data-id=\"e8c322a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"495\" height=\"702\" src=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-3.jpg\" class=\"attachment-large size-large wp-image-85776\" alt=\"Emailchef flow: anniversario contatto\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-3.jpg 495w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-3-212x300.jpg 212w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71dfb7c elementor-widget elementor-widget-text-editor\" data-id=\"71dfb7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seleziona la data che far\u00e0 scattare l\u2019automazione. Pu\u00f2 essere una data predefinita (come la data di iscrizione) o un campo personalizzato che hai creato (ad esempio \u201cData di nascita\u201d o \u201cData di scadenza\u201d).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc7b42b elementor-widget elementor-widget-heading\" data-id=\"dc7b42b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Decidi quando avviare il flusso.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-171a4e0 elementor-widget elementor-widget-image\" data-id=\"171a4e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"495\" height=\"702\" src=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-4.jpg\" class=\"attachment-large size-large wp-image-85785\" alt=\"Emailchef flow: anniversario contatto\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-4.jpg 495w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-4-212x300.jpg 212w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad5b12c elementor-widget elementor-widget-text-editor\" data-id=\"ad5b12c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Puoi far partire il flusso:<\/p>\n<ul>\n<li style=\"margin-bottom: 10px;\"><strong>Nella data dell&rsquo;anniversario<\/strong>: il contatto entra nel flusso esattamente quel giorno.<\/li>\n<li style=\"margin-bottom: 10px;\"><strong>Prima della data dell&rsquo;anniversario<\/strong>: scegli di quanti giorni anticipare l&rsquo;entrata nel flusso.<\/li>\n<li style=\"margin-bottom: 10px;\"><strong>Dopo la data dell&rsquo;anniversario<\/strong>: scegli di quanti giorni posticipare l&rsquo;entrata nel flusso.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-775397e elementor-widget elementor-widget-heading\" data-id=\"775397e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Imposta \u201cRientra nel Flow\u201d.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1f5f7f elementor-widget elementor-widget-image\" data-id=\"d1f5f7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"495\" height=\"702\" src=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-5.jpg\" class=\"attachment-large size-large wp-image-85794\" alt=\"Emailchef flow: anniversario contatto\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-5.jpg 495w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-5-212x300.jpg 212w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bfd809 elementor-widget elementor-widget-text-editor\" data-id=\"6bfd809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questa opzione controlla se e quando un contatto pu&ograve; ripetere la sequenza. Di default, un contatto entra nel flusso una sola volta.<\/p>\n<p>Attivando lo switch <em>Rientra nel Flow<\/em>, puoi ripetere la sequenza secondo le tue preferenze.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4bd3bda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bd3bda\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-48a774e\" data-id=\"48a774e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce16db9 elementor-widget elementor-widget-text-editor\" data-id=\"ce16db9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per maggiori informazioni, <a title=\"Guida sul rientro nel flow\" href=\"https:\/\/emailchef.com\/it\/documentazione\/flow-punti-di-entrata\/#repeat_flow\">leggi la guida completa sul <em>Rientro nel flow<\/em><\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-741cd27 elementor-widget elementor-widget-heading\" data-id=\"741cd27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. Imposta le condizioni di uscita.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20da53a elementor-widget elementor-widget-image\" data-id=\"20da53a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"495\" height=\"702\" src=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-6.jpg\" class=\"attachment-large size-large wp-image-85803\" alt=\"Emailchef flow: anniversario contatto\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-6.jpg 495w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto-6-212x300.jpg 212w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c050cd4 elementor-widget elementor-widget-text-editor\" data-id=\"c050cd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se lo desideri, puoi stabilire regole che interrompono il flusso se il contatto non soddisfa pi\u00f9 i criteri, cos\u00ec da mantenere la comunicazione sempre pertinente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-92ad699 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92ad699\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-681025c\" data-id=\"681025c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a53a04b elementor-widget elementor-widget-text-editor\" data-id=\"a53a04b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per maggiori informazioni, <a title=\"Guida sul rientro nel flow\" href=\"https:\/\/emailchef.com\/it\/documentazione\/flow-punti-di-entrata\/#exit_flow\">leggi la guida completa sulle <em>Condizioni di uscita<\/em><\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Il punto di entrata Anniversario del contatto si attiva in corrispondenza di una data specifica associata al contatto. Questa data pu&ograve; essere, ad esempio: la data di iscrizione alla tua lista; un campo personalizzato di tipo data, come la data di nascita, una scadenza o un anniversario particolare. Puoi scegliere di avviare il flusso esattamente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1081,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"g1_relation_tag":[],"class_list":["post-85747","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come configurare \u201cAnniversario del contatto\u201d in Emailchef Flow.<\/title>\n<meta name=\"description\" content=\"Questo punto di entrata si attiva in corrispondenza di una data specifica associata al contatto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/punto-di-entrata-anniversario-del-contatto\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/punto-di-entrata-anniversario-del-contatto\\\/\",\"name\":\"Come configurare \u201cAnniversario del contatto\u201d in Emailchef Flow.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/punto-di-entrata-anniversario-del-contatto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/punto-di-entrata-anniversario-del-contatto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/emailchef-flow-punto-ingresso-anniversario-contatto.jpg\",\"datePublished\":\"2025-09-01T09:48:14+00:00\",\"dateModified\":\"2025-09-11T08:35:38+00:00\",\"description\":\"Questo punto di entrata si attiva in corrispondenza di una data specifica associata al contatto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/punto-di-entrata-anniversario-del-contatto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/punto-di-entrata-anniversario-del-contatto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/punto-di-entrata-anniversario-del-contatto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/emailchef-flow-punto-ingresso-anniversario-contatto.jpg\",\"contentUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/emailchef-flow-punto-ingresso-anniversario-contatto.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/punto-di-entrata-anniversario-del-contatto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documentazione\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Punto di entrata: anniversario del contatto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come configurare \u201cAnniversario del contatto\u201d in Emailchef Flow.","description":"Questo punto di entrata si attiva in corrispondenza di una data specifica associata al contatto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/","url":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/","name":"Come configurare \u201cAnniversario del contatto\u201d in Emailchef Flow.","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/#primaryimage"},"thumbnailUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto.jpg","datePublished":"2025-09-01T09:48:14+00:00","dateModified":"2025-09-11T08:35:38+00:00","description":"Questo punto di entrata si attiva in corrispondenza di una data specifica associata al contatto.","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/#primaryimage","url":"https:\/\/emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto.jpg","contentUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2025\/09\/emailchef-flow-punto-ingresso-anniversario-contatto.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/punto-di-entrata-anniversario-del-contatto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Documentazione","item":"https:\/\/www.emailchef.com\/it\/documentazione\/"},{"@type":"ListItem","position":3,"name":"Punto di entrata: anniversario del contatto"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/85747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=85747"}],"version-history":[{"count":7,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/85747\/revisions"}],"predecessor-version":[{"id":87342,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/85747\/revisions\/87342"}],"up":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1081"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=85747"}],"wp:term":[{"taxonomy":"g1_relation_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/g1_relation_tag?post=85747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}