{"id":8324,"date":"2018-12-06T16:02:51","date_gmt":"2018-12-06T16:02:51","guid":{"rendered":"https:\/\/emailchef.com\/?page_id=8324"},"modified":"2021-07-27T09:54:03","modified_gmt":"2021-07-27T09:54:03","slug":"comunicazione-codice-destinatario-fatturazione-elettronica-come-fare","status":"publish","type":"page","link":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/","title":{"rendered":"Come comunicare il codice destinatario per la fatturazione elettronica"},"content":{"rendered":"<p>La legge di Bilancio 2018 ha introdotto, a partire dal 1 Gennaio 2019, l&#8217;<strong>obbligo di fatturazione elettronica<\/strong>.<\/p>\n<p>Al fine di adempiere al suddetto obbligo <strong>\u00e8 necessario<\/strong>:<\/p>\n<ol>\n<li>comunicare a tutti i propri fornitori il codice univoco destinatario<\/li>\n<li>richiedere a tutti clienti di inviare il loro codice univoco destinatario<\/li>\n<\/ol>\n<p>Probabilmente tutte le aziende stanno <strong>preparando una email in cui comunicano il proprio codice e richiedono quello del cliente<\/strong>, ma questo significa che ogni singola email e ogni singolo dato deve essere processato manualmente.<\/p>\n<p>Come fare quando il numero di clienti \u00e8 di centinaia, migliaia o anche pi\u00f9?<br \/>\nRegistrare il numero di codice univoco per ognuno dei clienti a mano sarebbe un compito immane che richiederebbe probabilmente mesi di lavoro.<\/p>\n<p>Seguono un <strong>video<\/strong> e una <strong>breve guida<\/strong> che ti mostrano come <strong>inviare una email personalizzata ad ogni singolo cliente<\/strong> e richiedere il codice univoco, permettendo di <strong>memorizzare automaticamente i dati<\/strong> (nome, cognome, partita IVA e codice univoco) sul vostro computer o su un foglio Google.<\/p>\n<p>Con questa operazione inoltre si ottiene l\u2019ulteriore beneficio di <strong>aggiornare velocemente la lista clienti<\/strong> e di avere un buon motivo per richiedere il consenso ad inviare comunicazioni commerciali via email ai clienti storici. Il dialogo costante con i propri clienti \u00e8 molto importante: al di l\u00e0 del carattere urgente dello scambio dei codici univoci, questa potrebbe essere una buona occasione per cominciare a comunicare periodicamente con i clienti.<\/p>\n<div class=\"g1-space\" style=\"height: 30px;\"><\/div>\n<h2><strong>Quale strumento?<\/strong><\/h2>\n<p>Per le comunicazioni via email <strong>\u00e8 consigliabile utilizzare un software<\/strong> professionale per l\u2019email marketing. <strong><a href=\"https:\/\/app.emailchef.com\/apps\/demo\/quicksignup\">Emailchef<\/a><\/strong> risponde perfettamente all&#8217;esigenza e consente di memorizzare i dati dei clienti direttamente nelle liste, per poi estrali in un comodo .csv da caricare su qualsiasi tipo di gestionale. Esistono due soluzioni per ottenere il risultato desiderato: vediamole insieme.<\/p>\n<div class=\"g1-space\" style=\"height: 30px;\"><\/div>\n<h2><strong>Guida<\/strong><\/h2>\n<h3><strong><span style=\"color: #ff6600;\">Soluzione A<\/span><\/strong><\/h3>\n<p>Per prima cosa dobbiamo <strong>creare la lista di clienti ai quali richiedere il codice<\/strong> per la fatturazione elettronica o altri eventuali dati: esporta dal tuo gestionale i dati in formato csv (un formato di scambio dati universale, supportato da tutti i gestionali).<\/p>\n<p>Quindi importa la lista in Emailchef. L\u2019importazione \u00e8 molto semplice: baster\u00e0 entrare nella sezione <em>\u201cListe\u201d<\/em>, creare una nuova lista, selezionare il file csv che hai esportato in precedenza e seguire le istruzioni del sistema.<\/p>\n<p><strong>Il prossimo passaggio \u00e8 molto importante<\/strong>: vai nella sezione della lista <em>&#8220;Campi Personalizzati&#8221;<\/em> e creane uno nuovo.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-8372 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41.png\" alt=\"screenshot_campo_personalizzato\" width=\"1293\" height=\"127\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41.png 1293w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41-300x29.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41-768x75.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41-1024x101.png 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41-968x95.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41-636x62.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41-320x31.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41-239x23.png 239w\" sizes=\"(max-width: 1293px) 100vw, 1293px\" \/><\/p>\n<p>Dagli il nome che preferisci, per esempio <em>&#8220;codice univoco fatturazione elettronica&#8221;<\/em> e <strong>ricordati di spuntare la casella<\/strong> &#8220;<em>Il contatto pu\u00f2 modificare questo campo?&#8221;<\/em>. In questo modo il tuo cliente avr\u00e0 la possibilit\u00e0 di <strong>inserire in autonomia il codice<\/strong>, salvandolo <strong>direttamente sulla tua lista<\/strong>.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-8379 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.10.04.png\" alt=\"screenshot_fatturazione_elettronica\" width=\"758\" height=\"512\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.10.04.png 758w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.10.04-300x203.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.10.04-636x430.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.10.04-320x216.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.10.04-239x161.png 239w\" sizes=\"(max-width: 758px) 100vw, 758px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Ricordati che puoi <strong>creare pi\u00f9 di un campo personalizzato<\/strong> e aggiungere per esempio anche il campo <em>&#8220;pec&#8221; o<\/em> altri dati aziendali per te utili da reperire. A questo punto <strong>scrivi il contenuto della email da inviare<\/strong> ai clienti; per l\u2019aspetto grafico <strong>puoi prendere spunto da uno dei modelli gi\u00e0 pronti<\/strong> forniti da Emailchef. Nella tua newsletter inserisci un testo chiaro o un pulsante ben visibile che i tuoi utenti dovranno cliccare per autocompilare il loro codice di fatturazione elettronica.<\/p>\n<p>Un esempio di comunicazione potrebbe essere il seguente:<\/p>\n<blockquote><p><em>Gentile [[ragione_sociale]],<\/em><\/p>\n<p><em>la legge di Bilancio 2018 ha introdotto, a partire dal 1 Gennaio 2019, l&#8217;obbligo di fatturazione elettronica.<\/em><\/p>\n<p><em>Al fine di adempiere al suddetto obbligo, dal 01\/01\/2019 provvederemo all&#8217;emissione ed invio delle fatture in formato elettronico XML attraverso il Sistema di Interscambio (SDI).<\/em><br \/>\n<em>La fattura inviata attraverso tale sistema sar\u00e0 l&#8217;unica valida per la registrazione ai fini fiscali.<\/em><\/p>\n<p><em>Per potervi recapitare i documenti fiscali \u00e8 necessario che, ENTRO IL 15 DICEMBRE 2018, ci comunichiate il Vs. codice identificativo di 7 caratteri ed il Vs. indirizzo PEC.<\/em><\/p>\n<p><em>Per farlo \u00e8 sufficiente cliccare qui.<\/em><\/p>\n<p><em>(INSERIRE LINK AGGIORNA LE TUE PREFERENZE)<\/em><\/p>\n<p><em>Per la ricezione, invece, della Vostra fatturazione elettronica, il nostro codice destinatario \u00e8 il seguente rispettivamente per:<\/em><br \/>\n<em>SOCIETA1 SRL: xxxxxxx<\/em><\/p>\n<p><em>Restando a disposizione, porgiamo i nostri pi\u00f9 cordiali saluti.<\/em><\/p>\n<p>&nbsp;<\/p><\/blockquote>\n<p><strong>Salva il template e procedi<\/strong> alla creazione della campagna cliccando su &#8220;<em>Salva e crea una campagna<\/em>&#8220;.<\/p>\n<p>Seleziona il testo o il pulsante che porter\u00e0 i tuoi utenti all&#8217;autocompilazione , premi il tasto sinistro del mouse e clicca su &#8220;<em>Inserisci\/Modifica link<\/em>&#8221; e <strong>inserisci questa esatta dicitura<\/strong>:&nbsp;[[change_preferences_link]] completa anche di parentesi quadre.<\/p>\n<p>A questo punto vai avanti nel processo di creazione della campagna fino a all&#8217;invio. Effettuando un test di prova potrai vedere che quando un utente riceve l&#8217;email e clicca sul bottone\/testo che gli hai indicato, si <strong>aprir\u00e0 automaticamente un form per l&#8217;autocompilazione<\/strong> del campo della fatturazione elettronica e gli altri suoi dati che volendo potete rendere ugualmente modificabili. Il form \u00e8 caricato sui nostri server con la <strong>comodit\u00e0 di essere protetto<\/strong> e <strong>risparmiarti la fatica di creare una nuova pagina<\/strong> sul tuo sito.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-8404 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2018\/12\/form-ec.jpg\" alt=\"screenshot_emailchef\" width=\"736\" height=\"839\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-ec.jpg 736w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-ec-263x300.jpg 263w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-ec-636x725.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-ec-320x365.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-ec-239x272.jpg 239w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/><\/p>\n<p>Appena l&#8217;utente inserir\u00e0 il dato e cliccher\u00e0 &#8220;<em>Aggiorna le tue preferenze<\/em>&#8221; <strong>il codice verr\u00e0 registrato automaticamente<\/strong> sulla tua lista.<br \/>\nLascia trascorrere qualche giorno per dare il tempo a tutti i tuoi utenti di procedere nella compilazione e poi potrai comodamente <strong>scaricare l&#8217;intero database dei codici operativi<\/strong> semplicemente andando su <em>Liste<\/em> &#8211;&gt; <em>Gestisci i contatti<\/em> e selezionando la voce<em> Esporta i contatti<\/em>.<\/p>\n<p>Otterrai il file csv di tutta la lista, comprendente anche la nuova colonna <em>&#8220;codice univoco fatturazione elettronica&#8221;<\/em>.<\/p>\n<div class=\"g1-space\" style=\"height: 30px;\"><\/div>\n<h3><strong><span style=\"color: #ff6600;\">Soluzione B<\/span><\/strong><\/h3>\n<p>Per questa modalit\u00e0 si prevede<strong> l&#8217;uso di Emailchef e un form di iscrizione Emailchef o Google Form<\/strong>. Gli step da seguire sono gli stessi del metodo precedente, fino al momento di creazione della campagna. Una volta creata la tua lista contatti e la tua newsletter, crea un <strong><a href=\"https:\/\/www.youtube.com\/watch?v=eQ3Hdq1PfeM\"><em>Form Emailchef<\/em><\/a><\/strong> o un <em>Form Google<\/em>, ed inserisci il relativo link nel corpo della mail come nel nostro precedente esempio. Suggeriamo di creare un <strong>form con pochi campi<\/strong>, quelli essenziali per individuare il cliente, ad esempio:<\/p>\n<ul>\n<li>Nome Azienda<\/li>\n<li>Nome PErsona<\/li>\n<li>Partita Iva<\/li>\n<li>Codice Univoco<\/li>\n<li>Indirizzo Email Pec<\/li>\n<\/ul>\n<p>Il risultato sar\u00e0 un modulo tipo questo:<\/p>\n<figure id=\"attachment_8336\" aria-describedby=\"caption-attachment-8336\" style=\"width: 1041px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8336 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1.png\" alt=\"\" width=\"1041\" height=\"1080\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1.png 1041w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1-289x300.png 289w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1-768x797.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1-987x1024.png 987w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1-968x1004.png 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1-636x660.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1-320x332.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/form-registrazione-fattura-elettronica-1-239x248.png 239w\" sizes=\"(max-width: 1041px) 100vw, 1041px\" \/><figcaption id=\"caption-attachment-8336\" class=\"wp-caption-text\">Immagine di un form creato con i Moduli di Google, bastano 2 minuti ed \u00e8 gratuito, tutti i dati vengono salvati sul vostro account Google, contatta il supporto per un aiuto.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>Otterrai un foglio Google<\/strong> simile a quello che segue, quindi facilmente consultabile anche utilizzando gli strumenti di ricerca a cui siamo abituati:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8343 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2018\/12\/informazioni-fatturazione-elettronica-google-fogli.png\" alt=\"\" width=\"827\" height=\"132\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/informazioni-fatturazione-elettronica-google-fogli.png 827w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/informazioni-fatturazione-elettronica-google-fogli-300x48.png 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/informazioni-fatturazione-elettronica-google-fogli-768x123.png 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/informazioni-fatturazione-elettronica-google-fogli-636x102.png 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/informazioni-fatturazione-elettronica-google-fogli-320x51.png 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2018\/12\/informazioni-fatturazione-elettronica-google-fogli-239x38.png 239w\" sizes=\"(max-width: 827px) 100vw, 827px\" \/><\/p>\n<p>Questo processo eviter\u00e0 la gestione manuale di ogni singola risposta per ogni email ricevuta, col relativo copia ed incolla a mano.<\/p>\n<div class=\"g1-space\" style=\"height: 30px;\"><\/div>\n<div id=\"\" class=\"g1-lead  \" >\n<p><strong>Se preferisci possiamo preparare la newsletter e il form per te, contattaci via chat, <a href=\"https:\/\/emailchef.com\/it\/contatti\/\">email<\/a> o telefono \ud83d\ude42<\/strong><\/p>\n<a id=\"\" class=\"g1-button g1-button--medium g1-button--solid g1-button--standard \" href=\"tel:0289050969\" title=\"\"> 02 89 050 969 <\/a>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Come richiedere e comunicare il CdI in pochi semplici passi<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"g1_relation_tag":[52],"class_list":["post-8324","page","type-page","status-publish","hentry","g1_relation_tag-gestione-liste-email"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come comunicare il codice destinatario per la fatturazione elettronica - Emailchef<\/title>\n<meta name=\"description\" content=\"Sistema per comunicare il codice univoco destinatario per la fatturazione elettronica in maniera automatica, evitando di perdere giornate di lavoro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\\\/\",\"name\":\"Come comunicare il codice destinatario per la fatturazione elettronica - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Schermata-2018-12-07-alle-11.08.41.png\",\"datePublished\":\"2018-12-06T16:02:51+00:00\",\"dateModified\":\"2021-07-27T09:54:03+00:00\",\"description\":\"Sistema per comunicare il codice univoco destinatario per la fatturazione elettronica in maniera automatica, evitando di perdere giornate di lavoro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Schermata-2018-12-07-alle-11.08.41.png\",\"contentUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/Schermata-2018-12-07-alle-11.08.41.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come comunicare il codice destinatario per la fatturazione elettronica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come comunicare il codice destinatario per la fatturazione elettronica - Emailchef","description":"Sistema per comunicare il codice univoco destinatario per la fatturazione elettronica in maniera automatica, evitando di perdere giornate di lavoro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/","url":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/","name":"Come comunicare il codice destinatario per la fatturazione elettronica - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41.png","datePublished":"2018-12-06T16:02:51+00:00","dateModified":"2021-07-27T09:54:03+00:00","description":"Sistema per comunicare il codice univoco destinatario per la fatturazione elettronica in maniera automatica, evitando di perdere giornate di lavoro.","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/#primaryimage","url":"https:\/\/emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41.png","contentUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2018\/12\/Schermata-2018-12-07-alle-11.08.41.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/comunicazione-codice-destinatario-fatturazione-elettronica-come-fare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come comunicare il codice destinatario per la fatturazione elettronica"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/8324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=8324"}],"version-history":[{"count":30,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/8324\/revisions"}],"predecessor-version":[{"id":46926,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/8324\/revisions\/46926"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=8324"}],"wp:term":[{"taxonomy":"g1_relation_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/g1_relation_tag?post=8324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}