{"id":5346,"date":"2017-01-05T13:32:27","date_gmt":"2017-01-05T13:32:27","guid":{"rendered":"http:\/\/emailchef.com\/?page_id=5346\/"},"modified":"2017-01-10T08:48:20","modified_gmt":"2017-01-10T08:48:20","slug":"abbiamo-preso-carico-la-tua-richiesta","status":"publish","type":"page","link":"https:\/\/www.emailchef.com\/it\/abbiamo-preso-carico-la-tua-richiesta\/","title":{"rendered":"Abbiamo preso in carico la tua richiesta!"},"content":{"rendered":"<p>Riceverai una email dal tuo consulente dedicato quanto prima!<br \/>\nBuona Giornata!<\/p>\n<p><em>Il Team Emailchef<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceverai una email dal tuo consulente dedicato quanto prima! Buona Giornata! Il Team Emailchef<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"g1_relation_tag":[],"class_list":["post-5346","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abbiamo preso in carico la tua richiesta! - Emailchef<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/abbiamo-preso-carico-la-tua-richiesta\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/abbiamo-preso-carico-la-tua-richiesta\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/abbiamo-preso-carico-la-tua-richiesta\\\/\",\"name\":\"Abbiamo preso in carico la tua richiesta! - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"datePublished\":\"2017-01-05T13:32:27+00:00\",\"dateModified\":\"2017-01-10T08:48:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/abbiamo-preso-carico-la-tua-richiesta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/abbiamo-preso-carico-la-tua-richiesta\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/abbiamo-preso-carico-la-tua-richiesta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abbiamo preso in carico la tua richiesta!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abbiamo preso in carico la tua richiesta! - Emailchef","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/abbiamo-preso-carico-la-tua-richiesta\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/abbiamo-preso-carico-la-tua-richiesta\/","url":"https:\/\/www.emailchef.com\/it\/abbiamo-preso-carico-la-tua-richiesta\/","name":"Abbiamo preso in carico la tua richiesta! - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"datePublished":"2017-01-05T13:32:27+00:00","dateModified":"2017-01-10T08:48:20+00:00","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/abbiamo-preso-carico-la-tua-richiesta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/abbiamo-preso-carico-la-tua-richiesta\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/abbiamo-preso-carico-la-tua-richiesta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Abbiamo preso in carico la tua richiesta!"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/5346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=5346"}],"version-history":[{"count":4,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/5346\/revisions"}],"predecessor-version":[{"id":5351,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/5346\/revisions\/5351"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=5346"}],"wp:term":[{"taxonomy":"g1_relation_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/g1_relation_tag?post=5346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}