{"id":2328,"date":"2014-09-22T12:58:49","date_gmt":"2014-09-22T12:58:49","guid":{"rendered":"http:\/\/emailchef.com\/?page_id=2328"},"modified":"2023-02-27T14:03:16","modified_gmt":"2023-02-27T14:03:16","slug":"crea-una-campagna-in-5-minuti","status":"publish","type":"page","link":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/","title":{"rendered":"Crea una campagna in 5 minuti"},"content":{"rendered":"<p>In questo articolo ti mostreremo come <strong>creare, spedire e analizzare una classica campagna email<\/strong> in pochi minuti. Naturalmente Emailchef presenta molte altre caratteristiche e funzionalit\u00e0: considera quindi questa semplice procedura come un\u2019introduzione al nostro sistema, e fai riferimento alla guida integrale per ulteriori informazioni.<\/p>\n<p>Pronto? Partiamo!<\/p>\n<h2><\/h2>\n<h2><strong>1. Valida un mittente<\/strong><\/h2>\n<p>Per prima cosa, hai bisogno di registrare un mittente da cui inviare le tue email. Entra in Emailchef e clicca &#8220;IMPOSTAZIONI&#8221; nel menu a sinistra. Clicca &#8220;MITTENTI VERIFICATI&#8221; sulla sinistra, poi premi il pulsante &#8220;AGGIUNGI UN NUOVO MITTENTE&#8221;.<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20.jpg\" rel=\"lightbox\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-26744 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20.jpg\" alt=\"\" width=\"1649\" height=\"710\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20.jpg 1649w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20-300x129.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20-768x331.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20-1024x441.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20-968x417.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20-636x274.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20-320x138.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20-239x103.jpg 239w\" sizes=\"(max-width: 1649px) 100vw, 1649px\" \/><\/a><\/p>\n<p>Compila i campi inserendo i dati del mittente e un indirizzo postale valido, poi clicca &#8220;SALVA&#8221;.<\/p>\n<p>Emailchef invier\u00e0 un&#8217;email di verifica all&#8217;indirizzo email del mittente. Clicca sul pulsante dell&#8217;email per validare il tuo mittente.<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_24.jpg\" rel=\"lightbox\"><img decoding=\"async\" class=\"alignnone wp-image-26760 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_24.jpg\" alt=\"\" width=\"648\" height=\"561\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_24.jpg 648w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_24-300x260.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_24-636x551.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_24-320x277.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_24-239x207.jpg 239w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><\/a><\/p>\n<h2><strong>2. Aggiungi i tuoi contatti<\/strong><\/h2>\n<p>Adesso devi creare una lista di destinatari a cui inviare la tua newsletter. Partendo dalla dashboard, seleziona &#8220;LISTE&#8221; nel menu a sinistra e clicca su \u201cCREA UNA NUOVA LISTA\u201d:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2.jpg\" rel=\"lightbox\"><img decoding=\"async\" class=\"alignnone wp-image-19246 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2.jpg\" alt=\"\" width=\"1568\" height=\"829\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2.jpg 1568w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2-300x159.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2-768x406.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2-1024x541.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2-968x512.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2-636x336.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2-320x169.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_2-239x126.jpg 239w\" sizes=\"(max-width: 1568px) 100vw, 1568px\" \/><\/a><\/p>\n<p>A questo punto dai un nome rilevante alla tua lista e aggiungi una breve descrizione, poi spunta le due caselle in basso per confermare che <strong>invierai la newsletter soltanto a indirizzi autorizzati, <\/strong>cio\u00e8 gli indirizzi di utenti che hanno esplicitamente dichiarato l\u2019intenzione di ricevere la tua newsletter. Clicca &#8220;CREA&#8221;.<\/p>\n<p>Una volta creata la lista, sei pronto per inserire i tuoi contatti. Puoi:<\/p>\n<ul>\n<li><strong>importare i contatti da un file<\/strong>&nbsp;nel formato .xls, .xlsx, .ods, .csv, o .txt, oppure da una URL esterna<span style=\"font-weight: 400;\">; puoi importare i contatti anche <\/span><span style=\"font-weight: 400;\">attraverso Google Contacts e Google Sheets<\/span><\/li>\n<li><strong>aggiungere i contatti singolarmente<\/strong>: baster\u00e0 immettere l&#8217;email del contatto e compilare il resto dei dati che hai a disposizione<\/li>\n<li><strong>copiare e incollare<\/strong> <strong>la lista di contatti da un file di testo<\/strong>; i dati di ogni contatto devono&nbsp;essere scritti su un&#8217;unica riga e intervallati da una virgola<\/li>\n<\/ul>\n<p>Puoi modificare i tuoi contatti in qualsiasi momento, cliccando su &#8220;MODIFICA&#8221;; per esempio aggiungendo il loro nome e cognome:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_3.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19286 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_3.jpg\" alt=\"\" width=\"668\" height=\"377\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_3.jpg 668w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_3-300x169.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_3-636x359.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_3-482x271.jpg 482w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_3-320x181.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/05\/Screenshot_3-239x135.jpg 239w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/><\/a><\/p>\n<p>Se vuoi aggiungere altri campi d\u2019informazione ai contatti, clicca su \u201cCampi personalizzati\u201d e procedi. Emailchef dispone anche di uno <strong>strumento apposito<\/strong> per creare e inserire sul tuo sito un modulo d\u2019iscrizione: il modo migliore per far crescere gli iscritti alla tua lista e incuriosire nuovi utenti. Per ulteriori informazioni a riguardo, <span style=\"font-weight: 400;\">&nbsp;consulta: \u201c<\/span><strong><a href=\"https:\/\/emailchef.com\/it\/documentazione\/creazione-modulo-iscrizione\/\">Creazione di un modulo di iscrizione<\/a><\/strong><span style=\"font-weight: 400;\">\u201d.<\/span><\/p>\n<p>Va bene, adesso sei pronto per creare la tua prima email!<\/p>\n<h2><strong>3. Crea e invia la tua email<\/strong><\/h2>\n<p>Clicca su \u201cCAMPAGNE\u201d nel menu a sinistra, poi seleziona il pulsante \u201cCREA UNA CAMPAGNA\u201d:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19322 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5.jpg\" alt=\"\" width=\"1521\" height=\"621\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5.jpg 1521w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5-300x122.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5-768x314.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5-1024x418.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5-968x395.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5-636x260.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5-320x131.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_5-239x98.jpg 239w\" sizes=\"(max-width: 1521px) 100vw, 1521px\" \/><\/a><\/p>\n<p>Qui puoi:<\/p>\n<ul>\n<li><strong>creare un template<\/strong> professionale utilizzando il nostro editor drag &amp; drop<\/li>\n<li><strong>scegliere un template gi\u00e0 pronto<\/strong> dal nostro archivio<\/li>\n<li><strong>caricare un template preesistente<\/strong> da un file HTML o da una URL esterna<\/li>\n<\/ul>\n<p>Per cominciare, ti consigliamo di usare uno dei nostri template gi\u00e0 pronti. Qui sotto puoi vedere come appare il layout nell&#8217;editor drag &amp; drop:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19336 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6.jpg\" alt=\"\" width=\"1520\" height=\"929\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6.jpg 1520w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6-300x183.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6-768x469.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6-1024x626.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6-968x592.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6-636x389.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6-320x196.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_6-239x146.jpg 239w\" sizes=\"(max-width: 1520px) 100vw, 1520px\" \/><\/a><\/p>\n<p>A questo punto puoi modificare il template come vuoi,&nbsp;<strong>aggiungendo i contenuti<\/strong> che desideri e personalizzandoli, per esempio caricando e posizionando nuove immagini, cambiando il colore o il tipo di carattere, creando un elenco puntato e, naturalmente, inserendo link esterni.<br \/>\nUna volta completata la newsletter, non ti resta che salvare e creare la tua campagna: <strong>scegli il nome e l\u2019oggetto<\/strong>, e specifica da quale mittente desideri che venga spedita la newsletter (puoi aggiungere eventualmente un nuovo indirizzo; puoi anche scegliere un indirizzo email di risposta diverso da quello di invio).<\/p>\n<p>Ricorda che in calce all\u2019email devono essere presenti i <strong>segnaposto per le informazioni relative al CAN-SPAM Act<\/strong>, oltre al <strong>link per la disiscrizione<\/strong> (nei template preimpostati sono gi\u00e0 presenti):<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_7.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19370 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_7.jpg\" alt=\"\" width=\"654\" height=\"209\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_7.jpg 654w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_7-300x96.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_7-636x203.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_7-320x102.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_7-239x76.jpg 239w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/><\/a><\/p>\n<p>I segnaposto verranno visualizzati dai tuoi destinatari come i dati dell\u2019attivit\u00e0 del mittente che vuoi usare.<br \/>\n<strong>Queste informazioni sono obbligatorie <\/strong>affinch\u00e9 tu possa inviare le tue newsletter. Puoi inserire i segnaposto per il CAN-SPAM Act e il link per la disiscrizione nel tuo template con l&#8217;editor drag &amp; drop: nella sezione &#8220;BLOCCHI&#8221; sulla destra,&nbsp; seleziona &#8220;Pi\u00e8 di pagina&#8221; e inserisci il blocco \u201cCAN-SPAM Act\u201d.<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19386 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08.jpg\" alt=\"\" width=\"1520\" height=\"928\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08.jpg 1520w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08-300x183.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08-768x469.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08-1024x625.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08-968x591.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08-636x388.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08-320x195.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_08-239x146.jpg 239w\" sizes=\"(max-width: 1520px) 100vw, 1520px\" \/><\/a><\/p>\n<p>Nel caso di un template statico, puoi aggiungere le informazioni con l&#8217;editor statico di Emailchef, selezionandole in &#8220;Link speciali&#8221;:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19460 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010.jpg\" alt=\"\" width=\"1598\" height=\"922\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010.jpg 1598w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010-300x173.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010-768x443.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010-1024x591.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010-968x559.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010-636x367.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010-320x185.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_010-239x138.jpg 239w\" sizes=\"(max-width: 1598px) 100vw, 1598px\" \/><\/a><\/p>\n<p>Torniamo alla preparazione della campagna: ricorda che l\u2019oggetto della tua email non dovrebbe mai superare i 50-60 caratteri e dovrebbe incuriosire i tuoi lettori! <span style=\"font-weight: 400;\">Oltre al soggetto potresti aggiungere anche un preheader, una breve frase introduttiva che comparir\u00e0 nella posta in arrivo di seguito al soggetto. Guarda questo esempio:<\/span><\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_0014.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-19516 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_0014.jpg\" alt=\"\" width=\"808\" height=\"464\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_0014.jpg 808w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_0014-300x172.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_0014-768x441.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_0014-636x365.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_0014-320x184.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_0014-239x137.jpg 239w\" sizes=\"(max-width: 808px) 100vw, 808px\" \/><\/a><\/p>\n<p>Prosegui selezionando&nbsp;<strong>la lista dei destinatari<\/strong> a cui inviare la tua newsletter. Qui sotto, per esempio, vedrai che abbiamo scelto l\u2019elenco denominato \u201cMarketing list\u201d, composto da 1502 contatti:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_100.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19430 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_100.jpg\" alt=\"\" width=\"926\" height=\"197\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_100.jpg 926w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_100-300x64.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_100-768x163.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_100-636x135.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_100-320x68.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_100-239x51.jpg 239w\" sizes=\"(max-width: 926px) 100vw, 926px\" \/><\/a><\/p>\n<p>Adesso sei pronto a spedire l\u2019email. \u00c8 consigliabile fare un controllo dello spam per evitare <strong>problemi di filtraggio<\/strong>: \u00e8 un passaggio molto rapido che puoi effettuare nella schermata di riepilogo della campagna, cliccando \u201cSPAM TEST\u201d. Verificato che sia tutto in ordine, non devi fare altro che decidere se mandare la tua email subito o programmarne l\u2019invio per un altro momento.<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19446 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11.jpg\" alt=\"\" width=\"1256\" height=\"580\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11.jpg 1256w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11-300x139.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11-768x355.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11-1024x473.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11-968x447.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11-636x294.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11-320x148.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_11-239x110.jpg 239w\" sizes=\"(max-width: 1256px) 100vw, 1256px\" \/><\/a><\/p>\n<h2><strong>4. Analizza la campagna<\/strong><\/h2>\n<p>Pensi che una volta inviata l\u2019email il lavoro sia finito? Tutto il contrario! Adesso \u00e8 il momento di controllare come \u00e8 andata: se \u00e8 stata o meno un successo. Emailchef ti fornisce un <strong>accurato strumento d\u2019analisi<\/strong>, aggiornato in tempo reale, che rileva i pi\u00f9 importanti dati d\u2019interazione tra la tua email e i tuoi abbonati.<\/p>\n<p>Clicca \u201cSTATISTICHE\u201d nel menu a sinistra e seleziona la campagna di cui vuoi visualizzare l\u2019andamento (in questo caso la tua prima in assoluto):<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19492 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13.jpg\" alt=\"\" width=\"1194\" height=\"235\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13.jpg 1194w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13-300x59.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13-768x151.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13-1024x202.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13-968x191.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13-636x125.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13-320x63.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_13-239x47.jpg 239w\" sizes=\"(max-width: 1194px) 100vw, 1194px\" \/><\/a><\/p>\n<p>Come puoi vedere da questi diagrammi, riceverai informazioni su:<\/p>\n<ul>\n<li><strong>consegna<\/strong> (quante email sono state consegnate e quante&nbsp;sono arrivate a destinazione)<\/li>\n<li><strong>apertura<\/strong> (quante email sono state aperte)<\/li>\n<li><strong>clic<\/strong>&nbsp;(quanti clic hanno ricevuto i link presenti nella tua email)<\/li>\n<li><strong>disiscrizioni<\/strong>&nbsp;(quanti utenti hanno cancellato la sottoscrizione alla newsletter)<\/li>\n<li><strong>bounce<\/strong> (quante email sono state respinte in arrivo dai server dei tuoi contatti)<\/li>\n<li><strong>reclami spam<\/strong> (quante volte la tua email \u00e8 stata segnalata come spam dai destinatari)<\/li>\n<\/ul>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19476 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012.jpg\" alt=\"\" width=\"1234\" height=\"647\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012.jpg 1234w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012-300x157.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012-768x403.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012-1024x537.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012-968x508.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012-636x333.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012-320x168.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_012-239x125.jpg 239w\" sizes=\"(max-width: 1234px) 100vw, 1234px\" \/><\/a><\/p>\n<p>Questo grafico a linee monitora invece l\u2019<strong>andamento della campagna nel tempo<\/strong>. Selezionando le voci sotto il grafico a linee, potrai vedere i trend di ogni categoria: email aperte, clic, disiscrizioni&#8230;<\/p>\n<p>Nella sezione delle statistiche potrai anche visualizzare la lista completa di tutti i contatti relativi a ogni singola categoria (indirizzo per indirizzo, chi ha aperto l\u2019email, chi ci ha cliccato dentro e cos\u00ec via, insieme al giorno e l\u2019ora in cui \u00e8 stata compiuta l\u2019azione).<\/p>\n<p>Inoltre potrai monitorare la performance dei singoli link della tua campagna e vedere da quali parti del mondo \u00e8 stata aperta la tua email:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19530 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16.jpg\" alt=\"\" width=\"1212\" height=\"732\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16.jpg 1212w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16-300x181.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16-768x464.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16-1024x618.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16-968x585.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16-636x384.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16-320x193.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_16-239x144.jpg 239w\" sizes=\"(max-width: 1212px) 100vw, 1212px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19544 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15.jpg\" alt=\"\" width=\"1207\" height=\"875\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15.jpg 1207w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15-300x217.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15-768x557.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15-1024x742.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15-968x702.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15-636x461.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15-320x232.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/06\/Screenshot_15-239x173.jpg 239w\" sizes=\"(max-width: 1207px) 100vw, 1207px\" \/><\/a><\/p>\n<p>Questi dati sono <strong>molto preziosi<\/strong> per migliorare le future campagne. Per esempio, se vedi che le statistiche di apertura della tua newsletter cominciano a diventare negative, vuol dire che forse \u00e8 ora di ripensare l\u2019oggetto delle mail o cambiare giorno e ora dell\u2019invio. Un numero molto alto di bounce, invece, vuol dire che devi assolutamente ripulire la tua lista di contatti, eliminando gli indirizzi doppi o scritti in maniera scorretta.<\/p>\n<p>&nbsp;<\/p>\n<p>E questo a conti fatti \u00e8 tutto. Anche se \u00e8 una <strong>semplice panoramica<\/strong>, ti abbiamo dimostrato quanto \u00e8 facile creare, inviare e analizzare una campagna email con Emailchef: ma questo \u00e8 solo il primo passo. Se desideri conoscere meglio il nostro sistema puoi esplorarlo con assoluta libert\u00e0 e se ne hai bisogno puoi consultare la nostra guida integrale.<\/p>\n<p>Oh, e ricorda: saremo sempre lieti di aiutarti e conoscere le tue opinioni.<\/p>\n<div class=\"centered\" style=\"position:relative;padding-bottom:56.25%;height:0;overflow:hidden;\">\n                <iframe\n                    src=\"https:\/\/www.youtube-nocookie.com\/embed\/sz3jqZt9e2A\"\n                    title=\"YouTube video\"\n                    style=\"position:absolute;top:0;left:0;width:100%;height:100%;\"\n                    frameborder=\"0\"\n                    allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\"\n                    allowfullscreen\n                    loading=\"lazy\">\n                <\/iframe>\n            <\/div>\n","protected":false},"excerpt":{"rendered":"<p>In questo articolo ti mostreremo come creare, spedire e analizzare una classica campagna email in pochi minuti. Naturalmente Emailchef presenta molte altre caratteristiche e funzionalit\u00e0: considera quindi questa semplice procedura come un\u2019introduzione al nostro sistema, e fai riferimento alla guida integrale per ulteriori informazioni. Pronto? Partiamo! 1. Valida un mittente Per prima cosa, hai bisogno [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":223,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"g1_relation_tag":[],"class_list":["post-2328","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crea una campagna email in 5 minuti - Emailchef<\/title>\n<meta name=\"description\" content=\"In questo articolo ti mostreremo come creare, spedire e analizzare una classica campagna email in pochi minuti con Emailchef.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/crea-una-campagna-in-5-minuti\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/crea-una-campagna-in-5-minuti\\\/\",\"name\":\"Crea una campagna email in 5 minuti - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/crea-una-campagna-in-5-minuti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/crea-una-campagna-in-5-minuti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Screenshot_20.jpg\",\"datePublished\":\"2014-09-22T12:58:49+00:00\",\"dateModified\":\"2023-02-27T14:03:16+00:00\",\"description\":\"In questo articolo ti mostreremo come creare, spedire e analizzare una classica campagna email in pochi minuti con Emailchef.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/crea-una-campagna-in-5-minuti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/crea-una-campagna-in-5-minuti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/crea-una-campagna-in-5-minuti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Screenshot_20.jpg\",\"contentUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Screenshot_20.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/crea-una-campagna-in-5-minuti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crea una campagna in 5 minuti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crea una campagna email in 5 minuti - Emailchef","description":"In questo articolo ti mostreremo come creare, spedire e analizzare una classica campagna email in pochi minuti con Emailchef.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/","url":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/","name":"Crea una campagna email in 5 minuti - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/#primaryimage"},"thumbnailUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20.jpg","datePublished":"2014-09-22T12:58:49+00:00","dateModified":"2023-02-27T14:03:16+00:00","description":"In questo articolo ti mostreremo come creare, spedire e analizzare una classica campagna email in pochi minuti con Emailchef.","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/#primaryimage","url":"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20.jpg","contentUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/10\/Screenshot_20.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/crea-una-campagna-in-5-minuti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Crea una campagna in 5 minuti"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/2328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=2328"}],"version-history":[{"count":56,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/2328\/revisions"}],"predecessor-version":[{"id":62592,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/2328\/revisions\/62592"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=2328"}],"wp:term":[{"taxonomy":"g1_relation_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/g1_relation_tag?post=2328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}