{"id":1424,"date":"2014-09-22T08:33:27","date_gmt":"2014-09-22T08:33:27","guid":{"rendered":"http:\/\/emailchef.com\/?page_id=1424"},"modified":"2024-12-05T11:28:15","modified_gmt":"2024-12-05T11:28:15","slug":"un-controllo-finale","status":"publish","type":"page","link":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/","title":{"rendered":"Un controllo finale"},"content":{"rendered":"<p>Prima di procedere con l\u2019invio della tua campagna, un riepilogo ti permette di controllare tutti gli elementi principali.<\/p>\n<p>In questa fase, puoi visualizzare l\u2019<strong>anteprima completa<\/strong> del template, della <strong>riga dell\u2019oggetto<\/strong>, del <strong>preheader<\/strong> e dell\u2019<strong>indirizzo del mittente<\/strong>.<\/p>\n<p>\u00c8 inoltre possibile verificare la <strong>lista<\/strong> e i <strong>segmenti <\/strong>selezionati, con un&#8217;indicazione del numero totale di destinatari.<\/p>\n<p>Se necessario, puoi ancora apportare modifiche per perfezionare i dettagli della tua campagna.<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale.jpg\" rel=\"lightbox\" title=\"Revisione finale invio campagna email marketing\"><img decoding=\"async\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale.jpg\" alt=\"Revisione finale invio campagna email marketing\" style=\"margin-top: 15px; margin-bottom: 15px;\" \/><\/a><\/p>\n<h2>Consigli utili prima di inviare<\/h2>\n<ul style=\"margin-top:30px;\">\n<li><strong>Email di test:<\/strong> ti consigliamo di inviarti un\u2019email di prova per verificare che tutto sia come desideri. Inserisci il tuo indirizzo (o quello preferito) e clicca su &#8220;INVIA L\u2019EMAIL DI TEST&#8221;.<br \/><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale-2.jpg\" rel=\"lightbox\" title=\"Revisione finale invio campagna email marketing\"><img decoding=\"async\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale-2.jpg\" alt=\"Revisione finale invio campagna email marketing\" style=\"margin-top: 15px; margin-bottom: 20px;\" \/><\/a><\/li>\n<li><strong>Spam test:<\/strong> effettua un controllo sul livello di spam della tua email. Il punteggio ottenuto ti aiuter\u00e0 a capire quanto \u00e8 probabile che il messaggio raggiunga la casella di posta principale dei tuoi destinatari, evitando la cartella spam. Il report dettagliato evidenzier\u00e0 eventuali punti deboli da migliorare.<br \/><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale-3.jpg\" rel=\"lightbox\" title=\"Revisione finale invio campagna email marketing\"><img decoding=\"async\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale-3.jpg\" alt=\"Revisione finale invio campagna email marketing\" style=\"margin-top: 15px; margin-bottom: 25px;\" \/><\/a><\/li>\n<\/ul>\n<p>Quando hai completato tutte le verifiche, clicca su &#8220;<strong>AVANTI<\/strong>&#8221; per procedere con l\u2019invio o con la programmazione della campagna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prima di procedere con l\u2019invio della tua campagna, un riepilogo ti permette di controllare tutti gli elementi principali. In questa fase, puoi visualizzare l\u2019anteprima completa del template, della riga dell\u2019oggetto, del preheader e dell\u2019indirizzo del mittente. \u00c8 inoltre possibile verificare la lista e i segmenti selezionati, con un&#8217;indicazione del numero totale di destinatari. Se necessario, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":1081,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"g1_relation_tag":[],"class_list":["post-1424","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un controllo finale - Emailchef<\/title>\n<meta name=\"description\" content=\"Prima di procedere con l&#039;invio, \u00e8 sempre una buona idea avviare uno spam test in grado di evidenziare ogni possibile \u201cpunto debole\u201d dei tuoi messaggi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/un-controllo-finale\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/un-controllo-finale\\\/\",\"name\":\"Un controllo finale - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/un-controllo-finale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/un-controllo-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/invio-campagna-email-marketing-revisione-finale.jpg\",\"datePublished\":\"2014-09-22T08:33:27+00:00\",\"dateModified\":\"2024-12-05T11:28:15+00:00\",\"description\":\"Prima di procedere con l'invio, \u00e8 sempre una buona idea avviare uno spam test in grado di evidenziare ogni possibile \u201cpunto debole\u201d dei tuoi messaggi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/un-controllo-finale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/un-controllo-finale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/un-controllo-finale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/invio-campagna-email-marketing-revisione-finale.jpg\",\"contentUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/invio-campagna-email-marketing-revisione-finale.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/un-controllo-finale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documentazione\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un controllo finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un controllo finale - Emailchef","description":"Prima di procedere con l'invio, \u00e8 sempre una buona idea avviare uno spam test in grado di evidenziare ogni possibile \u201cpunto debole\u201d dei tuoi messaggi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/","url":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/","name":"Un controllo finale - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale.jpg","datePublished":"2014-09-22T08:33:27+00:00","dateModified":"2024-12-05T11:28:15+00:00","description":"Prima di procedere con l'invio, \u00e8 sempre una buona idea avviare uno spam test in grado di evidenziare ogni possibile \u201cpunto debole\u201d dei tuoi messaggi.","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/#primaryimage","url":"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale.jpg","contentUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2024\/12\/invio-campagna-email-marketing-revisione-finale.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/un-controllo-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Documentazione","item":"https:\/\/www.emailchef.com\/it\/documentazione\/"},{"@type":"ListItem","position":3,"name":"Un controllo finale"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=1424"}],"version-history":[{"count":17,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1424\/revisions"}],"predecessor-version":[{"id":78016,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1424\/revisions\/78016"}],"up":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1081"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=1424"}],"wp:term":[{"taxonomy":"g1_relation_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/g1_relation_tag?post=1424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}