{"id":1335,"date":"2014-09-22T08:27:45","date_gmt":"2014-09-22T08:27:45","guid":{"rendered":"http:\/\/emailchef.com\/?page_id=1335"},"modified":"2023-02-27T10:37:38","modified_gmt":"2023-02-27T10:37:38","slug":"black-list-globale","status":"publish","type":"page","link":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/","title":{"rendered":"Black list globale"},"content":{"rendered":"<p>Dalla pagina della gestione delle liste, puoi accedere alla sezione &#8220;<strong>Blacklist\u00a0globale<\/strong>&#8221; cliccando l&#8217;apposito pulsante:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76.jpg\" rel=\"lightbox\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-21456 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76.jpg\" alt=\"\" width=\"1488\" height=\"408\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76.jpg 1488w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76-300x82.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76-768x211.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76-1024x281.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76-968x265.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76-636x174.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76-320x88.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76-239x66.jpg 239w\" sizes=\"(max-width: 1488px) 100vw, 1488px\" \/><\/a><\/p>\n<p>Nella blacklist globale trovi l&#8217;elenco di tutti gli <strong>indirizzi email\u00a0a cui non vengono pi\u00f9 inviati i tuoi messaggi. <\/strong>Fanno quindi parte di questa lista:<\/p>\n<ul>\n<li>gli <a href=\"https:\/\/emailchef.com\/it\/blog-emailchef-academy\/che-cosa-e-un-hard-bounce\/\" target=\"_blank\" rel=\"noopener\">hard bounce<\/a><\/li>\n<li>i contatti disiscritti<\/li>\n<li>i contatti che hanno segnalato il tuo mittente come spam<\/li>\n<\/ul>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80.jpg\" rel=\"lightbox\"><img decoding=\"async\" class=\"alignnone wp-image-21470 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80.jpg\" alt=\"\" width=\"1196\" height=\"470\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80.jpg 1196w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80-300x118.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80-768x302.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80-1024x402.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80-968x380.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80-636x250.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80-320x126.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_80-239x94.jpg 239w\" sizes=\"(max-width: 1196px) 100vw, 1196px\" \/><\/a><\/p>\n<p>Questi indirizzi vengono aggiunti in automatico alla tua blacklist, ma puoi anche <strong>aggiungere personalmente degli indirizzi<\/strong> a cui vuoi essere sicuro di non inviare pi\u00f9 email.<\/p>\n<p>Per farlo, clicca il pulsante &#8220;AGGIUNGI&#8221; e inserisci gli indirizzi email che vuoi inserire nella blacklist. <strong>\u00c8<\/strong>\u00a0<strong>possibile\u00a0anche aggiungere dei domini.<\/strong><\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_81.jpg\" rel=\"lightbox\"><img decoding=\"async\" class=\"alignnone wp-image-21486 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_81.jpg\" alt=\"\" width=\"722\" height=\"442\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_81.jpg 722w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_81-300x184.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_81-636x389.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_81-320x196.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_81-239x146.jpg 239w\" sizes=\"(max-width: 722px) 100vw, 722px\" \/><\/a><\/p>\n<p>Infine, clicca &#8220;SALVA&#8221;.<\/p>\n<p>Gli indirizzi email aggiunti alla blacklist vengono segnalati in rosso nelle tue liste:<\/p>\n<p><a href=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82.jpg\" rel=\"lightbox\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-21516 size-full\" src=\"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82.jpg\" alt=\"\" width=\"1198\" height=\"698\" srcset=\"https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82.jpg 1198w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82-300x175.jpg 300w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82-768x447.jpg 768w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82-1024x597.jpg 1024w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82-968x564.jpg 968w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82-636x371.jpg 636w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82-320x186.jpg 320w, https:\/\/www.emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_82-239x139.jpg 239w\" sizes=\"(max-width: 1198px) 100vw, 1198px\" \/><\/a><\/p>\n<p>Anche se vengono mostrati tra i contatti attivi, questi indirizzi verranno scartati in fase di invio delle email.<\/p>\n<p>Per approfondire l&#8217;argomento, guarda questo video tutorial:<\/p>\n<p><iframe  id=\"_ytid_61911\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Z_ZhhQuEF70?autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=light&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalla pagina della gestione delle liste, puoi accedere alla sezione &#8220;Blacklist\u00a0globale&#8221; cliccando l&#8217;apposito pulsante: Nella blacklist globale trovi l&#8217;elenco di tutti gli indirizzi email\u00a0a cui non vengono pi\u00f9 inviati i tuoi messaggi. Fanno quindi parte di questa lista: gli hard bounce i contatti disiscritti i contatti che hanno segnalato il tuo mittente come spam Questi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":1081,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"g1_relation_tag":[],"class_list":["post-1335","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Black list globale - Emailchef<\/title>\n<meta name=\"description\" content=\"In questa pagina puoi aggiungere gli indirizzi a cui non inviare pi\u00f9 alcuna email, indipendentemente dal fatto che risultino iscritti a una o pi\u00f9 liste.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/black-list-globale\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/black-list-globale\\\/\",\"name\":\"Black list globale - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/black-list-globale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/black-list-globale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Screenshot_76.jpg\",\"datePublished\":\"2014-09-22T08:27:45+00:00\",\"dateModified\":\"2023-02-27T10:37:38+00:00\",\"description\":\"In questa pagina puoi aggiungere gli indirizzi a cui non inviare pi\u00f9 alcuna email, indipendentemente dal fatto che risultino iscritti a una o pi\u00f9 liste.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/black-list-globale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/black-list-globale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/black-list-globale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Screenshot_76.jpg\",\"contentUrl\":\"https:\\\/\\\/emailchef.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Screenshot_76.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/black-list-globale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documentazione\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/it\\\/documentazione\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Black list globale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"Gustose ricette di email marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Black list globale - Emailchef","description":"In questa pagina puoi aggiungere gli indirizzi a cui non inviare pi\u00f9 alcuna email, indipendentemente dal fatto che risultino iscritti a una o pi\u00f9 liste.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/","url":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/","name":"Black list globale - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/#primaryimage"},"image":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/#primaryimage"},"thumbnailUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76.jpg","datePublished":"2014-09-22T08:27:45+00:00","dateModified":"2023-02-27T10:37:38+00:00","description":"In questa pagina puoi aggiungere gli indirizzi a cui non inviare pi\u00f9 alcuna email, indipendentemente dal fatto che risultino iscritti a una o pi\u00f9 liste.","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/#primaryimage","url":"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76.jpg","contentUrl":"https:\/\/emailchef.com\/wp-content\/uploads\/2020\/07\/Screenshot_76.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/it\/documentazione\/black-list-globale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/it\/"},{"@type":"ListItem","position":2,"name":"Documentazione","item":"https:\/\/www.emailchef.com\/it\/documentazione\/"},{"@type":"ListItem","position":3,"name":"Black list globale"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"Gustose ricette di email marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/comments?post=1335"}],"version-history":[{"count":14,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1335\/revisions"}],"predecessor-version":[{"id":62515,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1335\/revisions\/62515"}],"up":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/pages\/1081"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/media?parent=1335"}],"wp:term":[{"taxonomy":"g1_relation_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/it\/wp-json\/wp\/v2\/g1_relation_tag?post=1335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}