{"id":10799,"date":"2019-07-16T08:33:32","date_gmt":"2019-07-16T08:33:32","guid":{"rendered":"https:\/\/emailchef.com\/?page_id=10799"},"modified":"2019-07-16T12:23:12","modified_gmt":"2019-07-16T12:23:12","slug":"nachrichten-updates","status":"publish","type":"page","link":"https:\/\/www.emailchef.com\/de\/nachrichten-updates\/","title":{"rendered":"Nachrichten &#038; Updates"},"content":{"rendered":"<p>[app_news_show]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[app_news_show]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"g1_relation_tag":[],"class_list":["post-10799","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachrichten &amp; Updates - Emailchef<\/title>\n<meta name=\"description\" content=\"Entdecken Sie die neuesten Nachrichten und Updates aus der Emailchef-Welt\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emailchef.com\/de\/nachrichten-updates\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/de\\\/nachrichten-updates\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/de\\\/nachrichten-updates\\\/\",\"name\":\"Nachrichten & Updates - Emailchef\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\"},\"datePublished\":\"2019-07-16T08:33:32+00:00\",\"dateModified\":\"2019-07-16T12:23:12+00:00\",\"description\":\"Entdecken Sie die neuesten Nachrichten und Updates aus der Emailchef-Welt\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/de\\\/nachrichten-updates\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.emailchef.com\\\/de\\\/nachrichten-updates\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/de\\\/nachrichten-updates\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.emailchef.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachrichten &#038; Updates\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#website\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"name\":\"Emailchef\",\"description\":\"K\u00f6stliche Rezepte f\u00fcr E-Mail-Marketing\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.emailchef.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#organization\",\"name\":\"Delivery Tech Corp.\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"contentUrl\":\"https:\\\/\\\/www.emailchef.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo-sama.png\",\"width\":237,\"height\":80,\"caption\":\"Delivery Tech Corp.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.emailchef.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachrichten & Updates - Emailchef","description":"Entdecken Sie die neuesten Nachrichten und Updates aus der Emailchef-Welt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emailchef.com\/de\/nachrichten-updates\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emailchef.com\/de\/nachrichten-updates\/","url":"https:\/\/www.emailchef.com\/de\/nachrichten-updates\/","name":"Nachrichten & Updates - Emailchef","isPartOf":{"@id":"https:\/\/www.emailchef.com\/#website"},"datePublished":"2019-07-16T08:33:32+00:00","dateModified":"2019-07-16T12:23:12+00:00","description":"Entdecken Sie die neuesten Nachrichten und Updates aus der Emailchef-Welt","breadcrumb":{"@id":"https:\/\/www.emailchef.com\/de\/nachrichten-updates\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emailchef.com\/de\/nachrichten-updates\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.emailchef.com\/de\/nachrichten-updates\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emailchef.com\/de\/"},{"@type":"ListItem","position":2,"name":"Nachrichten &#038; Updates"}]},{"@type":"WebSite","@id":"https:\/\/www.emailchef.com\/#website","url":"https:\/\/www.emailchef.com\/","name":"Emailchef","description":"K\u00f6stliche Rezepte f\u00fcr E-Mail-Marketing","publisher":{"@id":"https:\/\/www.emailchef.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emailchef.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.emailchef.com\/#organization","name":"Delivery Tech Corp.","url":"https:\/\/www.emailchef.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","contentUrl":"https:\/\/www.emailchef.com\/wp-content\/uploads\/2022\/04\/logo-sama.png","width":237,"height":80,"caption":"Delivery Tech Corp."},"image":{"@id":"https:\/\/www.emailchef.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/pages\/10799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/comments?post=10799"}],"version-history":[{"count":1,"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/pages\/10799\/revisions"}],"predecessor-version":[{"id":10801,"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/pages\/10799\/revisions\/10801"}],"wp:attachment":[{"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/media?parent=10799"}],"wp:term":[{"taxonomy":"g1_relation_tag","embeddable":true,"href":"https:\/\/www.emailchef.com\/de\/wp-json\/wp\/v2\/g1_relation_tag?post=10799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}